{"id":1968,"date":"2023-08-08T13:35:16","date_gmt":"2023-08-08T04:35:16","guid":{"rendered":"https:\/\/sell-hk.allu-official.com\/brand\/tiffany\/"},"modified":"2024-02-28T17:04:49","modified_gmt":"2024-02-28T08:04:49","slug":"tiffany","status":"publish","type":"brand","link":"https:\/\/sell-hk.allu-official.com\/en\/tiffany\/","title":{"rendered":"Tiffany &#038; Co."},"content":{"rendered":"<div class=\"lazyblock-visual-imgarea-Z96gLf wp-block-lazyblock-visual-imgarea\"><section class=\"p-visual\">\n    <div class=\"p-visual__imageArea\">\n      <div class=\"p-visual__imageContents\">\n          <h1 class=\"p-visual__heading\">\n        <span class=\"p-visual__headingLead\">Competitive Valuation!<\/span>\n        <span class=\"p-visual__headingTitle\">Sell Your Tiffany &amp; Co. at ALLU Today!<\/span>\n      <\/h1>\n          <div class=\"p-visual__cta\">\n                        <div class=\"p-visual__ctaItem\">\n                              <a href=\"https:\/\/api.whatsapp.com\/send?phone=85298898591&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" target=\"_blank\" class=\"p-visual__ctaButton--whatsapp\" rel=\"noopener\">Get a Quote<\/a>\n                          <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"p-visual__imageBlock\">\n        <div class=\"p-visual__image\">\n            <!-- GLOBAL_VJ_MARKTING-674 -->\n                                            <!-- PC\uff1a\u5e38\u306b\u30c7\u30d5\u30a9\u30eb\u30c8 -->\n                <img decoding=\"async\" class=\"u-onlyPc\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_tiffany.png\" alt=\"Tiffany &#038; Co.\" width=\"640\" height=\"500\">\n                <!-- SP\uff1a\u767b\u9332\u753b\u50cf\u304c\u3042\u308c\u3070\u305d\u308c\u3001\u306a\u3051\u308c\u3070\u30c7\u30d5\u30a9\u30eb\u30c8 -->\n                <img decoding=\"async\" class=\"u-onlySp\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_tiffany.png\" alt=\"Tiffany &#038; Co.\" width=\"640\" height=\"500\">\n                    <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n<div class=\"p-introduction\">\n  <p class=\"p-introduction__text\">Tiffany &amp; Co. is a brand loved worldwide, and its trademark blue box has long been a symbol of Tiffany&#039;s quality. If you want to sell your Tiffany &amp; Co. items at high prices, please take advantage of our free appraisals.<\/p>\n<\/div><\/div>\n\n\n<!--more-->\n\n\n<div class=\"lazyblock-abouttext-2aQGNC wp-block-lazyblock-abouttext\"><section class=\"p-aboutText\">\n  <h2 class=\"p-aboutText__title--brand u-mx-10Sp\">Sell Your Tiffany &amp; Co. at ALLU<\/h2>\n  <p class=\"p-aboutText__text\">Tiffany &#038; Co., the world-famous jeweller hailing from New York City. In the world of haute couture jewellery, there exists a collection catalogue that contains only the rarest one-of-a-kind masterpieces of the craft \u2014 the &#8220;Blue Book.&#8221; This catalogue has been published annually for over 170 years, since its first edition in 1845, captivating the eyes and hearts of celebrities and collectors worldwide as the apex of jewellery compilations and, at the same time, a chronicle of the Tiffany &#038; Co. brand.<br \/>\n<br \/>\nFounded in 1837 by Charles Lewis Tiffany, the company found its trademark colour, known as Tiffany Blue, 15 years later. There is actually an intriguing episode related to the usage of the light medium robin egg blue colour. In the Victorian era, this colour was allegedly used as a marker for essential items and a symbol of nobility and truth. Tiffany &#038; Co. gained worldwide recognition also thanks to &#8220;Breakfast at Tiffany&#8217;s,&#8221; the famous 1961 movie starring Audrey Hepburn, which led the brand to establish an immutable position as a favourite of women worldwide.<br \/>\n<br \/>\nFrom the best-selling Open Heart necklace to the finest diamond jewels, bridal jewellery, silver, and gold products, the eternal brilliance of Tiffany jewellery never ceases to captivate the eyes and hearts of all beholders. Beyond the well-known open heart items, the brand&#8217;s pride and joy \u2014 the Tiffany setting diamond ring, and many more breathtaking masterpieces of jewellery craft, Tiffany &#038; Co also produces highly popular watches and accessories. The joy and delight of adoring yourself with a Tiffany piece is shared by all ages and generations.<br \/>\n<br \/>\nAt ALLU, we actively purchase many Tiffany &#038; Co. products at high prices. Our Value Designers, sustained by a wealth of experience and well-honed research skills, will carefully and accurately evaluate your items to provide a competitive appraisal. If you are considering selling your Tiffany &#038; Co. or other branded items, please take advantage of our services at ALLU.<\/p>\n<\/section><\/div>\n\n<div class=\"lazyblock-brandrecord-1OlRwX wp-block-lazyblock-brandrecord\"><section class=\"p-brandRecord\">\n  <h2 class=\"p-brandRecord__title\">Tiffany &amp; Co. Market Price Examples<\/h2>\n\n  <ul class=\"p-brandRecord__list\">\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/RT021708.jpg\" alt=\"Tiffany &amp; Co. Hardware 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2650.60<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hardware 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">11<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019194.jpg\" alt=\"Tiffany &amp; Co. buttons 925\u00d7750 Cuffs Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">722.89<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. buttons 925\u00d7750 Cuffs Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,117<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,847<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3021352.jpg\" alt=\"Tiffany &amp; Co. Triple Star 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">598.48<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Triple Star 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP082691.jpg\" alt=\"Tiffany &amp; Co. Milgrain Band Ring 750(PG)\u00d7Pt950 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2094.67<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Milgrain Band Ring 750(PG)\u00d7Pt950 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">275<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">894<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3030259.jpg\" alt=\"Tiffany &amp; Co. 1837 Narrow 925 Piercing jewelry (for both ears) Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1256.80<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. 1837 Narrow 925 Piercing jewelry (for both ears) Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">14<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3029836.jpg\" alt=\"Tiffany &amp; Co. Double Open Heart 925\u00d7750 Necklace Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1615.89<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Double Open Heart 925\u00d7750 Necklace Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">426<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,467<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3008871.jpg\" alt=\"Tiffany &amp; Co. Double Loving Heart Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3411.32<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Double Loving Heart Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">198<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">684<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020558.jpg\" alt=\"Tiffany &amp; Co. Signature Cross 925\u00d7750 Necklace Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">957.56<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Signature Cross 925\u00d7750 Necklace Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">719<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,477<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3015736.jpg\" alt=\"Tiffany &amp; Co. Leather Shoulder bag Gray AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3203.88<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Leather Shoulder bag Gray AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">30<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">177<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3012480.jpg\" alt=\"Tiffany &amp; Co. Hardware Pearl Earrings 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">15302.30<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hardware Pearl Earrings 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,117<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,847<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3014371.jpg\" alt=\"Tiffany &amp; Co. Open Heart Hoop Earrings 750(YG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">9416.80<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Open Heart Hoop Earrings 750(YG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">890<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,064<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019898.jpg\" alt=\"Tiffany &amp; Co. Infinity 925\u00d7750 Ring Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1483.28<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Infinity 925\u00d7750 Ring Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">312<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,075<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3026270.jpg\" alt=\"Tiffany &amp; Co. Twist 925 Bangle Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">711.97<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Twist 925 Bangle Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">4<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">46<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3024899.jpg\" alt=\"Tiffany &amp; Co. Return To Tiffany Heart Tag 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">652.64<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Return To Tiffany Heart Tag 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">33<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020572.jpg\" alt=\"Tiffany &amp; Co. By the Yard 1P 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">889.97<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 1P 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019239.jpg\" alt=\"Tiffany &amp; Co. Hardware small rink 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10086.30<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hardware small rink 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">5<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">57<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3028366.jpg\" alt=\"Tiffany &amp; Co. Return To Tiffany Mini Double Heart Tag 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">830.64<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Return To Tiffany Mini Double Heart Tag 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3030089.jpg\" alt=\"Tiffany &amp; Co. Sugar Stack 925 Ring Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1364.62<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Sugar Stack 925 Ring Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3026660.jpg\" alt=\"Tiffany &amp; Co. Small Cross 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">533.98<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Small Cross 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3025739.jpg\" alt=\"Tiffany &amp; Co. By the Yard 1P 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1067.96<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 1P 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3015930.jpg\" alt=\"Tiffany &amp; Co. Necklace chain 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1898.60<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Necklace chain 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">274<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">945<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020569.jpg\" alt=\"Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1067.96<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">625<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,151<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3028694.jpg\" alt=\"Tiffany &amp; Co. By the Yard 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1245.95<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020342.jpg\" alt=\"Tiffany &amp; Co. T Smile small Diamond Necklace 750(PG) A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10679.61<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile small Diamond Necklace 750(PG) A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">208<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">717<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019471.jpg\" alt=\"Tiffany &amp; Co. Fleur-de-Lys stem Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3559.87<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Fleur-de-Lys stem Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">179<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">619<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020570.jpg\" alt=\"Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1067.96<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">625<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,151<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3022905.jpg\" alt=\"Tiffany &amp; Co. combination hook &amp; eye 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">949.30<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. combination hook &amp; eye 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,165<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,010<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020567.jpg\" alt=\"Tiffany &amp; Co. 1837 Narrow 925 Bangle Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1245.95<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. 1837 Narrow 925 Bangle Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">4<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">52<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019370.jpg\" alt=\"Tiffany &amp; Co. Fleur-de-Lys stem Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3559.87<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Fleur-de-Lys stem Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">179<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">619<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3025721.jpg\" alt=\"Tiffany &amp; Co. Toggle 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1364.62<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Toggle 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">27<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3013761.jpg\" alt=\"Tiffany &amp; Co. Victoria Diamond Ring Pt950 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3085.22<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Victoria Diamond Ring Pt950 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">132<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">430<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020564.jpg\" alt=\"Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">830.64<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">20<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020568.jpg\" alt=\"Tiffany &amp; Co. Twist chain 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2135.92<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Twist chain 925\u00d7750 Bracelet Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,335<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,597<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP082508.jpg\" alt=\"Tiffany &amp; Co. Elsa Peretti Mesh 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2707.33<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Elsa Peretti Mesh 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">6<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">68<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3013397.jpg\" alt=\"Tiffany &amp; Co. Olive Leaf 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2471.91<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Olive Leaf 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">15<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3016672.jpg\" alt=\"Tiffany &amp; Co. Crown of hearts 925 x diamond Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">773.81<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Crown of hearts 925 x diamond Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.02<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">0.1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011683.jpg\" alt=\"Tiffany &amp; Co. 1837 Cushion 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">534.85<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. 1837 Cushion 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">17<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3007918.jpg\" alt=\"Tiffany &amp; Co. Hardware double 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3869.05<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hardware double 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">15<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP082710.jpg\" alt=\"Tiffany &amp; Co. Stud Diamond Earrings Pt950 G AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8239.70<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Stud Diamond Earrings Pt950 G AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">122<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">397<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3014752.jpg\" alt=\"Tiffany &amp; Co. T Smile Diamond Bracelet 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8828.25<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile Diamond Bracelet 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">217<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">749<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3014034.jpg\" alt=\"Tiffany &amp; Co. T Smile Mini Necklace 750(PG) A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3531.30<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile Mini Necklace 750(PG) A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">217<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">749<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP082887.jpg\" alt=\"Tiffany &amp; Co. Bow Diamond Necklace Pt950 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">7062.60<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Bow Diamond Necklace Pt950 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">158<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">513<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3014370.jpg\" alt=\"Tiffany &amp; Co. Open Heart Necklace 750(YG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">20010.70<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Open Heart Necklace 750(YG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2,150<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">7,401<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020783.jpg\" alt=\"Tiffany &amp; Co. Solitaire Diamond Necklace Pt950 Diamond diameter about 3.60 mm AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2648.48<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Solitaire Diamond Necklace Pt950 Diamond diameter about 3.60 mm AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">122<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">397<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP082687.jpg\" alt=\"Tiffany &amp; Co. Soleste Diamond Necklace Pt950 I AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10005.35<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Soleste Diamond Necklace Pt950 I AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">153<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">496<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020779.jpg\" alt=\"Tiffany &amp; Co. T Smile small Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">11771.00<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile small Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">227<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">782<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP082688.jpg\" alt=\"Tiffany &amp; Co. Victoria small Diamond Necklace Pt950 A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">14713.75<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Victoria small Diamond Necklace Pt950 A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">132<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">430<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019948.jpg\" alt=\"Tiffany &amp; Co. T Smile small Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4237.56<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile small Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">284<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">978<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2856061.jpg\" alt=\"Tiffany &amp; Co. By the Yard 1P Diamond Necklace Pt950 Approx. 4.41 mm in diameter AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2177.64<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 1P Diamond Necklace Pt950 Approx. 4.41 mm in diameter AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">127<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">414<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2590414.jpg\" alt=\"Tiffany &amp; Co. Paper flowers Cluster Diamond Necklace Pt950 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">14713.75<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Paper flowers Cluster Diamond Necklace Pt950 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">449<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,457<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020566.jpg\" alt=\"Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">765.12<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">21<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020565.jpg\" alt=\"Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">823.97<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">19<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3019376.jpg\" alt=\"Tiffany &amp; Co. Knot 925\u00d7750 Ring Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">529.70<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Knot 925\u00d7750 Ring Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">246<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">847<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3024373.jpg\" alt=\"Tiffany &amp; Co. Infinity 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1059.39<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Infinity 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020563.jpg\" alt=\"Tiffany &amp; Co. Atlas 925 Bangle Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">882.83<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Atlas 925 Bangle Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">29<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3020562.jpg\" alt=\"Tiffany &amp; Co. Atlas 925 Bangle Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">706.26<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Atlas 925 Bangle Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">29<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3024032.jpg\" alt=\"Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">765.12<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">19<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3028351.jpg\" alt=\"Tiffany &amp; Co. Hardware Micro Link 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3119.32<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hardware Micro Link 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.9<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">9<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3028692.jpg\" alt=\"Tiffany &amp; Co. By the Yard 1P 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">823.97<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 1P 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3028693.jpg\" alt=\"Tiffany &amp; Co. Somerset Narrow 925 Ring Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1294.81<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Somerset Narrow 925 Ring Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2698104.jpg\" alt=\"Tiffany &amp; Co. Metro 60874875 SS QZ Silver-Face A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">16071.43<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Metro 60874875 SS QZ Silver-Face A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3016179.jpg\" alt=\"Tiffany &amp; Co. Love Knot 925\u00d7750 Ring Silver x gold AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">655.47<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Love Knot 925\u00d7750 Ring Silver x gold AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">274<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">945<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011680.jpg\" alt=\"Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">834.24<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">22<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3016180.jpg\" alt=\"Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Ring Silver x gold AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">715.06<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Ring Silver x gold AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">350<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,206<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3018382.jpg\" alt=\"Tiffany &amp; Co. 1837 Plastic Sunglass 56\u25a118 145 Brown x blue AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">595.24<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. 1837 Plastic Sunglass 56\u25a118 145 Brown x blue AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.6<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011709.jpg\" alt=\"Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Ring Silver x gold AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">655.47<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Hook &amp; Eye 925\u00d7750 Ring Silver x gold AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">426<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,467<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011306.jpg\" alt=\"Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">834.24<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Venetian 925 Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">22<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011675.jpg\" alt=\"Tiffany &amp; Co. Love Knot 925\u00d7750 Earrings (for both ears) Silver x gold AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">715.06<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Love Knot 925\u00d7750 Earrings (for both ears) Silver x gold AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">236<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">815<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3008698.jpg\" alt=\"Tiffany &amp; Co. By the Yard 1P Diamond Necklace 750(PG) Diameter approx. 3.70mm AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2562.30<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 1P Diamond Necklace 750(PG) Diameter approx. 3.70mm AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">198<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">684<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/HX054186.jpg\" alt=\"Tiffany &amp; Co. Solitaire Diamond Necklace Pt950 Diamond diameter approx. 3.90mm AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3396.53<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Solitaire Diamond Necklace Pt950 Diamond diameter approx. 3.90mm AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">122<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">397<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011892.jpg\" alt=\"Tiffany &amp; Co. Return To Tiffany Mini Double Heart Tag 925 Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">834.24<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Return To Tiffany Mini Double Heart Tag 925 Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3011340.jpg\" alt=\"Tiffany &amp; Co. T Smile Mini Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">7746.48<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile Mini Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">217<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">749<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3015488.jpg\" alt=\"Tiffany &amp; Co. Paloma Picasso 925 Piercing jewelry (for both ears) Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">536.29<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Paloma Picasso 925 Piercing jewelry (for both ears) Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">14<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/YF028517.jpg\" alt=\"Tiffany &amp; Co. By the Yard 1P Diamond Necklace 750(YG) Approx. 4.80 mm in diameter AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3809.52<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. By the Yard 1P Diamond Necklace 750(YG) Approx. 4.80 mm in diameter AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">189<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">652<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3016724.jpg\" alt=\"Tiffany &amp; Co. Olive Leaf 925 x pearl Necklace Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1011.90<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Olive Leaf 925 x pearl Necklace Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3016456.jpg\" alt=\"Tiffany &amp; Co. Chain Cross Heart 925\u00d714K Necklace Gold \u00d7 Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">892.86<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Chain Cross Heart 925\u00d714K Necklace Gold \u00d7 Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">596<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,054<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3005235.jpg\" alt=\"Tiffany &amp; Co. Edge bypassing Narrow Diamond Ring 750(YG)\u00d7Pt950 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">17857.14<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Edge bypassing Narrow Diamond Ring 750(YG)\u00d7Pt950 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">367<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,192<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3006868.jpg\" alt=\"Tiffany &amp; Co. T Smile small Necklace 750(PG) A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4940.48<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. T Smile small Necklace 750(PG) A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">255<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">880<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3009702.jpg\" alt=\"Tiffany &amp; Co. Atlas Open medallions Diamond Code Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">5952.38<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Atlas Open medallions Diamond Code Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">985<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,390<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3016175.jpg\" alt=\"Tiffany &amp; Co. Return To Tiffany Mini heart tag beads 925 x diamond Bracelet Silver AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">1071.43<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Tiffany &amp; Co. Return To Tiffany Mini heart tag beads 925 x diamond Bracelet Silver AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">0.05<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">0.3<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n  <\/ul>\n  <div class=\"p-brandRecord__more js-brandRecordMore\">View More<\/div>\n  <p class=\"p-brandRecord__notes\">*The above prices are for reference only (tax included) and do not guarantee the actual selling price. The actual price may vary depending on the item&#039;s condition, the inclusion of accessories, the date of manufacture, market fluctuations, and stock availability.<\/p>\n<\/section>\n<\/div>\n\n\n\n<div class=\"lazyblock-google-DY5BR wp-block-lazyblock-google\"><section class=\"p-userComment \" id=\"customer-review\">\n  <h2 class=\"p-userComment__title\">\n  Selling Tiffany &#038; Co. at ALLU: Google Reviews<\/h2>\n\n  <!-- WP Google Review Slider -->\n  <div class=\"p-googleReviewSlider\">\n    <div class=\"p-googleReviewSlider__container\" data-loaded=\"false\">\n    <style>#wprev-slider-1 .wprev_preview_bradius_T1 {border-radius: 0px;}#wprev-slider-1 .wprev_preview_bg1_T1::after{ border-top: 30px solid ; }<\/style><style><\/style><div class=\"wprev-no-slider revnotsameheight\" id=\"wprev-slider-1\">\t\t<div class=\"wprevpro_t1_outer_div w3_wprs-row-padding\">\r\n\t\t\t\t<div class=\"wprevpro_t1_DIV_1 w3_wprs-col l12\">\r\n\t\t\t<div class=\"indrevdiv wprevpro_t1_DIV_2 wprev_preview_bg1_T1 wprev_preview_tcolor1_T1 wprev_preview_bradius_T1\">\r\n\t\t\t\t<p class=\"wprevpro_t1_P_3 wprev_preview_tcolor1_T1\">\r\n\t\t\t\t\t<span class=\"wprevpro_star_imgs_T1\"><span class=\"starloc1 wprevpro_star_imgs wprevpro_star_imgsloc1\"><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><\/span><\/span>First class service\ud83d\udc4d\ud83c\udffb\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><span class=\"wprevpro_t1_A_8\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXuS_jO_pg3d4bRLO6-8XOw9E_-X91FJ9x9Z9Vjw76JgUWKW6nM=s128-c0x00000000-cc-rp-mo?sz=100\" alt=\"Jenny Avatar\" class=\"wprevpro_t1_IMG_4\" loading=\"lazy\" \/><\/span> <span class=\"wprevpro_t1_SPAN_5 wprev_preview_tcolor2_T1\">Jenny<br\/><span class=\"wprev_showdate_T1\"><\/span> <\/span>\r\n\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"wprevpro_t1_outer_div w3_wprs-row-padding\">\r\n\t\t\t\t<div class=\"wprevpro_t1_DIV_1 w3_wprs-col l12\">\r\n\t\t\t<div class=\"indrevdiv wprevpro_t1_DIV_2 wprev_preview_bg1_T1 wprev_preview_tcolor1_T1 wprev_preview_bradius_T1\">\r\n\t\t\t\t<p class=\"wprevpro_t1_P_3 wprev_preview_tcolor1_T1\">\r\n\t\t\t\t\t<span class=\"wprevpro_star_imgs_T1\"><span class=\"starloc1 wprevpro_star_imgs wprevpro_star_imgsloc1\"><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><\/span><\/span>Nice\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><span class=\"wprevpro_t1_A_8\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLHLr5WfIYcP_PvxXnIu5skiZW8Bv2DkaVJ4K7zTLR48S0nwqM=s128-c0x00000000-cc-rp-mo?sz=100\" alt=\"Flora Hsu Avatar\" class=\"wprevpro_t1_IMG_4\" loading=\"lazy\" \/><\/span> <span class=\"wprevpro_t1_SPAN_5 wprev_preview_tcolor2_T1\">Flora H.<br\/><span class=\"wprev_showdate_T1\"><\/span> <\/span>\r\n\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"wprevpro_t1_outer_div w3_wprs-row-padding\">\r\n\t\t\t\t<div class=\"wprevpro_t1_DIV_1 w3_wprs-col l12\">\r\n\t\t\t<div class=\"indrevdiv wprevpro_t1_DIV_2 wprev_preview_bg1_T1 wprev_preview_tcolor1_T1 wprev_preview_bradius_T1\">\r\n\t\t\t\t<p class=\"wprevpro_t1_P_3 wprev_preview_tcolor1_T1\">\r\n\t\t\t\t\t<span class=\"wprevpro_star_imgs_T1\"><span class=\"starloc1 wprevpro_star_imgs wprevpro_star_imgsloc1\"><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><\/span><\/span>Decent and swift service! Recommend!\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><span class=\"wprevpro_t1_A_8\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIs-AtxM-goZ1HL7XGVh0NUHmJCQ-ZovSou524f9EQZ7PCu3g=s128-c0x00000000-cc-rp-mo?sz=100\" alt=\"Meave Lai Avatar\" class=\"wprevpro_t1_IMG_4\" loading=\"lazy\" \/><\/span> <span class=\"wprevpro_t1_SPAN_5 wprev_preview_tcolor2_T1\">Meave L.<br\/><span class=\"wprev_showdate_T1\"><\/span> <\/span>\r\n\t\t<\/div>\r\n\t\t<\/div>\r\n<\/div>\r\n    <\/div>\n  <\/div>\n<\/section><\/div>\n\n\n\n<div class=\"lazyblock-cta-ZePQyh wp-block-lazyblock-cta\"><div class=\"p-cta\">\n  <div class=\"p-cta__inner\">\n    <div class=\"p-cta__title\">\n            <p class=\"p-cta__titleText\">How to Sell Luxury Goods at ALLU<\/p>\n    <\/div>\n    <ul class=\"p-cta__list\">\n      <li class=\"p-cta__listItem--shop\">\n        <a href=\"\/en\/store-service\/\" class=\"p-cta__listLink--shop\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Sell to Store\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_store.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Sell at Store<\/p>\n            <p class=\"p-cta__listLinkSub\">The quickest way to get cash<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n      <\/li>\n                  <li class=\"p-cta__listItem--whats\">\n                <a target=\"_blank\" href=\"https:\/\/api.whatsapp.com\/send?phone=85298898591&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" class=\"p-cta__listLink--whats\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Chat on WhatsApp\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_sns.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Chat on WhatsApp<\/p>\n            <p class=\"p-cta__listLinkSub\">Contact Us<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n              <\/li>\n    <\/ul>\n  <\/div>\n<\/div><\/div>\n\n<div class=\"lazyblock-imperfectitems-ZWJ1Ai wp-block-lazyblock-imperfectitems\"><section class=\"p-imperfectItems\">\n  <div class=\"p-imperfectItems__container--top\">\n    <div class=\"p-imperfectItems__heading\">\n      <h2 class=\"p-imperfectItems__title\">\n        <span class=\"p-imperfectItems__title--small u-mt0\">ALLU can purchase<\/span>Imperfect Items<span class=\"p-imperfectItems__title--small\">Rejected by Competitors<\/span>      <\/h2>\n    <\/div>\n    <div class=\"p-imperfectItems__tableWrapper\">\n      <table class=\"p-imperfectItems__table\">\n        <tbody>\n          <tr class=\"p-imperfectItems__tableList\">\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Discolouration<\/p>\n            <\/td>\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Engravings<\/p>\n            <\/td>\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Worn Edges<\/p>\n            <\/td>\n          <\/tr>\n          <tr class=\"p-imperfectItems__tableList\">\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Scratches<\/p>\n            <\/td>\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Poor Condition<\/p>\n            <\/td>\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Damaged<\/p>\n            <\/td>\n          <\/tr>\n          <tr class=\"p-imperfectItems__tableList\">\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Loose Pieces<\/p>\n            <\/td>\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Sticky Interior<\/p>\n            <\/td>\n            <td class=\"p-imperfectItems__tableItem\">\n              <p class=\"p-imperfectItems__tableText\">Stains Etc.<\/p>\n            <\/td>\n          <\/tr>\n        <\/tbody>\n      <\/table>\n    <\/div>\n  <\/div>\n  <div class=\"p-imperfectItems__container  is-none\">\n    <div class=\"p-imperfectItems__inner\">\n      <div class=\"p-imperfectItems__unit\">\n      <\/div>\n      <div class=\"p-imperfectItems__column\">\n      <\/div>\n    <\/div>\n  <\/div>\n  <div class=\"p-imperfectItems__container  is-none\">\n    <h2 class=\"c-headingMain\">Example of Purchased Imperfect Items at ALLU<\/h2>\n    <div class=\"p-imperfectItems__list\">\n      <div class=\"p-imperfectItems__listItem\">\n        <div class=\"p-imperfectItems__listThumbnail\">\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Herm\u00e8s Bearn Soufflet Wallet\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-01-01.webp\"><\/div>\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Herm\u00e8s Bearn Soufflet Wallet\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-01-02.webp\"><\/div>\n        <\/div>\n        <div class=\"p-imperfectItems__listTag\">Purchase Date: January 2021<\/div>\n        <h3 class=\"p-imperfectItems__listTitle\">Herm\u00e8s Bearn Soufflet Wallet<\/h3>\n        <div class=\"p-imperfectItems__listInner\">\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Selling Price<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">HK$440.00<\/dd>\n          <\/dl>\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Rank<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">B<\/dd>\n          <\/dl>\n        <\/div>\n        <p class=\"p-imperfectItems__listText\">Year: 2001<br>Material: Box Calf<br>Damaged with scuffs, stains, and fraying on the exterior and interior. Metal fittings are also scratched and peeling.<\/p>\n      <\/div>\n      <div class=\"p-imperfectItems__listItem\">\n        <div class=\"p-imperfectItems__listThumbnail\">\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Louis Vuitton Monogram Speedy 25\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-02-01.webp\"><\/div>\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Louis Vuitton Monogram Speedy 25\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-02-02.webp\"><\/div>\n        <\/div>\n        <div class=\"p-imperfectItems__listTag\">Purchase Date: February 2021<\/div>\n        <h3 class=\"p-imperfectItems__listTitle\">Louis Vuitton Monogram Speedy 25<\/h3>\n        <div class=\"p-imperfectItems__listInner\">\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Selling Price<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">HK$880.00<\/dd>\n          <\/dl>\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Rank<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">B<\/dd>\n          <\/dl>\n        <\/div>\n        <p class=\"p-imperfectItems__listText\">Year: 1994<br>Damaged with tears in the pull leather area. Scuffs and discolouration on the exterior and handles and scuffs on the interior. Metal fittings are also scratched.<\/p>\n      <\/div>\n      <div class=\"p-imperfectItems__listItem\">\n        <div class=\"p-imperfectItems__listThumbnail\">\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Louis Vuitton Damier Azur Pochette Bosphore\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-03-01.webp\"><\/div>\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Louis Vuitton Damier Azur Pochette Bosphore\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-03-02.webp\"><\/div>\n        <\/div>\n        <div class=\"p-imperfectItems__listTag\">Purchase Date: February 2021<\/div>\n        <h3 class=\"p-imperfectItems__listTitle\">Louis Vuitton Damier Azur Pochette Bosphore<\/h3>\n        <div class=\"p-imperfectItems__listInner\">\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Selling Price<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">HK$880.00<\/dd>\n          <\/dl>\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Rank<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">B<\/dd>\n          <\/dl>\n        <\/div>\n        <p class=\"p-imperfectItems__listText\">Year: 2007          <br>Item fabric damage with stains and scuffs on the outside and inside. Metal fittings are also scratched.<\/p>\n      <\/div>\n      <div class=\"p-imperfectItems__listItem\">\n        <div class=\"p-imperfectItems__listThumbnail\">\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Louis Vuitton Monogram Keepall 45\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-04-01.webp\"><\/div>\n          <div class=\"p-imperfectItems__listImage\"><img loading=\"lazy\" decoding=\"async\" alt=\"Louis Vuitton Monogram Keepall 45\" width=\"300\" height=\"300\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/item\/lv202108-bag-04-02.webp\"><\/div>\n        <\/div>\n        <div class=\"p-imperfectItems__listTag\">Purchase Date: October 2020<\/div>\n        <h3 class=\"p-imperfectItems__listTitle\">Louis Vuitton Monogram Keepall 45<\/h3>\n        <div class=\"p-imperfectItems__listInner\">\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Selling Price<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">HK$220.00<\/dd>\n          <\/dl>\n          <dl class=\"p-imperfectItems__listRow\">\n            <dt class=\"p-imperfectItems__listLabel\">Rank<\/dt>\n            <dd class=\"p-imperfectItems__listLabel--red\">C<\/dd>\n          <\/dl>\n        <\/div>\n        <p class=\"p-imperfectItems__listText\">Damaged handles with discolouration on the exterior and scuffs on the interior and handles. Metal fittings are also scratched.<\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section><\/div>\n\n<div class=\"lazyblock-purchaseitems-ZTeXEz wp-block-lazyblock-purchaseitems\"><section class=\"p-purchaseItems\">\n  <h2 class=\"c-headingMain\">What We Buy at ALLU<\/h2>\n<!-- GLOBAL_VJ_MARKTING-672 -->\n    <div class=\"u-onlyPc\">\n        <ul class=\"p-purchaseItems__list\">\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_gold.webp\" alt=\"Gold and Precious Metals\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Gold and Precious Metals<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_watch.webp\" alt=\"Watches\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Watches<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_bag.webp\" alt=\"Brand Bags\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Brand Bags<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_wallet.webp\" alt=\"Brand Wallets\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Brand Wallets<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_jewelry.webp\" alt=\"Jewellery\" width=\"107\" height=\"107\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Jewellery<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_accessory.webp\" alt=\"Accessories\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Accessories<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_antique.webp\" alt=\"Antiques\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/>\n            <\/div><span class=\"p-purchaseItems__listLabel\">Antiques<\/span><\/li>\n        <\/ul>\n        <h3 class=\"p-purchaseItems__subtitle\"><span class=\"p-purchaseItems__subtitleInner\">\u25a0 Items You Can Sell<\/span><\/h3>\n        <p class=\"p-purchaseItems__text\">Bags, pouches, tote bags, business bags, boston bags, clutches, travel bags, shoulder bags, wallets, card cases, passport holders, key cases, wristwatches, mules, sandals, oxfords, pumps, boots, pair rings, rings, necklaces, pendants, piercings, earrings, brooches, bracelets, gloves, belts, pens, wrist bands, anklets, accessories, eyewear, hats and caps, handkerchiefs, neckties, stoles, scarves, bangles, etc.<\/p>\n    <\/div>\n\n    <section class=\"p-topCategoryBox u-onlySp\">\n    <div class=\"p-topCategoryBox__inner\">\n        <div class=\"p-topCategoryBox__container\">\n        <div class=\"p-topCategoryBox__item\">\n            <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/watches\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_watch.webp\" alt=\"Sell your luxury watches.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">WATCH<br\/><span class=\"p-topCategoryBox__titleSub\">Sell your luxury watches.<\/span><\/h4>\n            <\/a>\n        <\/div>\n        <div class=\"p-topCategoryBox__item\">\n                        <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/gold\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_gold.webp\" alt=\"Sell your gold and precious metals.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">GOLD<br\/><span class=\"p-topCategoryBox__titleSub\">Sell your gold and precious metals.<\/span><\/h4>\n            <\/a>\n                    <\/div>\n        <div class=\"p-topCategoryBox__item\">\n            <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/bags\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_bag.webp\" alt=\"Sell your branded bags and wallets.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">BAGS<br\/><span class=\"p-topCategoryBox__titleSub\">Sell your branded bags and wallets.<\/span><\/h4>\n            <\/a>\n        <\/div>\n        <div class=\"p-topCategoryBox__item\">\n            <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/jewelry\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_jewelry.webp\" alt=\"Sell your precious jewellery and gemstones.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">JEWELLERY<br\/>\n            <span class=\"p-topCategoryBox__titleSub\">Sell your precious jewellery and gemstones.<\/span><\/h4>\n            <\/a>\n        <\/div>\n        <\/div>\n        <div class=\"p-topCategoryBox__info\">\n        <h3 class=\"p-topCategoryBox__infoTitle\">Luxury Articles We Buy Back<\/h3>\n        <div class=\"p-topCategoryBox__infoBody\">\n            <p class=\"p-topCategoryBox__infoText\">Watches, jewelry, bags, wallets, accessories, clothing, shoes, antiques, gold and precious metals. For other items, please <a class=\"p-topCategoryBox__infoTextRink\"  href=\"https:\/\/api.whatsapp.com\/send?phone=33619259635&#038;text=Bonjour%2C%20je%20souhaite%20prendre%20rendez-vous%20dans%20votre%20bureau%20d%27achat%20pour%20vendre%20mes%20articles%20de%20luxe\" target=\"_blank\" rel=\"noopener\">contact us<\/a> for details.<\/p>\n        <\/div>\n        <\/div>\n    <\/section>\n\n\n<\/section><\/div>\n\n<div class=\"lazyblock-cta-Z2uQnT4 wp-block-lazyblock-cta\"><div class=\"p-cta\">\n  <div class=\"p-cta__inner\">\n    <div class=\"p-cta__title\">\n            <p class=\"p-cta__titleText\">How to Sell Luxury Goods at ALLU<\/p>\n    <\/div>\n    <ul class=\"p-cta__list\">\n      <li class=\"p-cta__listItem--shop\">\n        <a href=\"\/en\/store-service\/\" class=\"p-cta__listLink--shop\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Sell to Store\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_store.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Sell at Store<\/p>\n            <p class=\"p-cta__listLinkSub\">The quickest way to get cash<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n      <\/li>\n                  <li class=\"p-cta__listItem--whats\">\n                <a target=\"_blank\" href=\"https:\/\/api.whatsapp.com\/send?phone=85298898591&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" class=\"p-cta__listLink--whats\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Chat on WhatsApp\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_sns.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Chat on WhatsApp<\/p>\n            <p class=\"p-cta__listLinkSub\">Contact Us<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n              <\/li>\n    <\/ul>\n  <\/div>\n<\/div><\/div>\n\n<div class=\"lazyblock-whychoose-Z1cnlYU wp-block-lazyblock-whychoose\">\n<section class=\"p-whyChoose u-mt0\">\n  <h2 class=\"p-whyChoose__title\">ALLU Offers Much More than High Selling Prices!<\/h2>\n  <div class=\"p-whyChoose__reason\">\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead--no01\">\n        <picture class=\"p-whyChoose__reasonNum--no01\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason01_gold.png\" media=\"(min-width: 768px)\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" alt=\"1\" width=\"100\" height=\"130\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason01_gold_sp.png\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle--no01\">Reliable, credible, and trustworthy appraisals<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody--no01\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap--no01\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason01.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" alt=\"Our knowledgeable and experienced experts provide accurate appraisals\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason01_sp.webp\" width=\"235\" height=\"150\" loading=\"lazy\" decoding=\"async\" \/>\n          <\/picture>\n          <div class=\"p-whyChoose__reasonBodyImgCaption\">Appraisal and Customer Service Training<\/div>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText--no01\">Our staff undergo thorough training under the tutelage of specialists in various fields, such as watches and jewellery, that allow us to provide the most accurate, detailed, and credible appraisals. We conduct periodic in-house tests to ensure our employees maintain their expertise and develop new skills. As professionals, we constantly strive to improve our skills to provide the most competitive appraisals.<\/p>\n      <\/div>\n    <\/div>\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead\">\n        <picture class=\"p-whyChoose__reasonNum\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason02_gold.png\" media=\"(min-width: 768px)\">\n          <img class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason02_gold_sp.png\" alt=\"2\" width=\"100\" height=\"130\" loading=\"lazy\" decoding=\"async\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle--no02\">Focus on providing high-quality customer service<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap--left\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason02.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason02_sp.webp\" alt=\"Focus on providing high-quality customer service\" loading=\"lazy\" decoding=\"async\">\n          <\/picture>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText\">We make the selling process as simple as possible, and our staff ensures that our customers understand and are satisfied with each appraisal.<\/p>\n      <\/div>\n    <\/div>\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead\">\n        <picture class=\"p-whyChoose__reasonNum\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason03_gold.png\" media=\"(min-width: 768px)\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason03_gold_sp.png\" alt=\"3\" width=\"100\" height=\"130\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle\">We purchase a wide variety of items and brands<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap--no03\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason03.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason03_sp.webp\" alt=\"We purchase a wide variety of items and brands\" loading=\"lazy\" decoding=\"async\">\n          <\/picture>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText--no03\">We cater for an extensive range of items and brands and actively consider items in all conditions, even items our competitors may refuse to buy.<\/p>\n      <\/div>\n    <\/div>\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead\">\n        <picture class=\"p-whyChoose__reasonNum\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason04_gold.png\" media=\"(min-width: 768px)\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason04_gold_sp.png\" alt=\"4\" width=\"100\" height=\"130\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle\">No selling quantity or price limits<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap--left\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason04.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason04_sp.webp\" alt=\"No selling quantity or price limits\" loading=\"lazy\" decoding=\"async\">\n          <\/picture>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText\">For customers with large amounts or significantly expensive items, we buy and pay on the day without any limits in quantity or value.<\/p>\n      <\/div>\n    <\/div>\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead\">\n        <picture class=\"p-whyChoose__reasonNum\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason05_gold.png\" media=\"(min-width: 768px)\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason05_gold_sp.png\" alt=\"5\" width=\"100\" height=\"130\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle\">Quick and easy appraisals<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason05.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason05_sp.webp\" alt=\"Quick and easy appraisals\" loading=\"lazy\" decoding=\"async\">\n          <\/picture>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText\">Through our expert proficiency and globally vast product data collection, we provide speedy appraisals with minimal waiting time.<\/p>\n      <\/div>\n    <\/div>\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead\">\n        <picture class=\"p-whyChoose__reasonNum\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason06_gold.png\" media=\"(min-width: 768px)\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason06_gold_sp.png\" alt=\"6\" width=\"100\" height=\"130\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle--no06\">Stress-free and private spaces<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap--left\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason06.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason06_sp.webp\" alt=\"Stress-free and private spaces\" loading=\"lazy\" decoding=\"async\">\n          <\/picture>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText\">We strive to create the most stress-free selling experience with store spaces designed to ensure comfort and privacy.<\/p>\n      <\/div>\n    <\/div>\n    <div class=\"p-whyChoose__reasonItem\">\n      <div class=\"p-whyChoose__reasonHead\">\n        <picture class=\"p-whyChoose__reasonNum\">\n          <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason07_gold.png\" media=\"(min-width: 768px)\">\n          <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason07_gold_sp.png\" alt=\"7\" width=\"100\" height=\"130\">\n        <\/picture>\n        <h3 class=\"p-whyChoose__reasonTitle\">Conveniently located stores<\/h3>\n      <\/div>\n      <div class=\"p-whyChoose__reasonBody\">\n        <div class=\"p-whyChoose__reasonBodyImgWrap\">\n          <picture class=\"p-whyChoose__reasonBodyImgArea\">\n            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason07.webp\" media=\"(min-width: 768px)\">\n            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason07_sp.webp\" alt=\"Conveniently located stores\" loading=\"lazy\" decoding=\"async\">\n          <\/picture>\n        <\/div>\n        <p class=\"p-whyChoose__reasonBodyText\">ALLU stores are located in central areas for convenient access. Feel free to stop by while shopping or on the way home.<\/p>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section><\/div>\n\n<div class=\"lazyblock-storeinformation-Z2gymKG wp-block-lazyblock-storeinformation\"><section class=\"p-storeInformation\" id=\"shop-list\"><div class=\"p-storeInformation__inner\"><h2 class=\"p-storeInformation__title\">Shop Information<\/h2><ul class=\"p-storeInformation__list\"><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"Room A2, 16\/F ,Emperor Watch And Jewellery Centre, 8 Russell St, Causeway Bay\" width=\"1280\" height=\"854\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Causeway-Bay_3.jpg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">ALLU HK Causeway Bay Shop<\/h3><address class=\"p-storeInformation__itemAddress\">Room A2, 16\/F ,Emperor Watch And Jewellery Centre, 8 Russell St, Causeway Bay<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/causeway-bay-shop\/\">View ALLU HK Causeway Bay Shop Details<\/a><\/div><\/div><\/li><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"18\/F, Stanley 11, 11 Stanley St, Central, Hong Kong Island, Hong Kong\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Central_1.jpeg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">Central Shop<\/h3><address class=\"p-storeInformation__itemAddress\">18\/F, Stanley 11, 11 Stanley St, Central, Hong Kong Island, Hong Kong<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/central-shop\/\">View Central Shop Details<\/a><\/div><\/div><\/li><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"Room 503-4, 5\/F, Hanford Commercial Centre, 221B-E Nathan Road, Kowloon\" width=\"1280\" height=\"854\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Jordan_2.jpg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">ALLU HK Jordan Shop<\/h3><address class=\"p-storeInformation__itemAddress\">Room 503-4, 5\/F, Hanford Commercial Centre, 221B-E Nathan Road, Kowloon<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/jordan-shop\/\">View ALLU HK Jordan Shop Details<\/a><\/div><\/div><\/li><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"Room 1802, 18\/F, One Pacific Centre, 414 Kwun Tong Rd, Kwun Tong\" width=\"1280\" height=\"853\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Kwun-Tong_2.jpg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">ALLU HK Kwun Tong Shop<\/h3><address class=\"p-storeInformation__itemAddress\">Room 1802, 18\/F, One Pacific Centre, 414 Kwun Tong Rd, Kwun Tong<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/kwun-tong-shop\/\">View ALLU HK Kwun Tong Shop Details<\/a><\/div><\/div><\/li><\/ul><\/div><\/section><\/div>\n\n<div class=\"lazyblock-personalid-1I9gBt wp-block-lazyblock-personalid\"><div class=\"p-personalId\">\n  <p class=\"p-personalId__title\">\n        <span class=\"p-personalId__titleText\">You Need to Show Valid Identification to Sell at ALLU!<\/span>\n      <\/p>\n  <div class=\"p-personalId__body\">\n    <div class=\"p-personalId__box\">\n      <div class=\"p-personalId__boxTitle\">Required Form of Identification<\/div>\n      <ul class=\"p-personalId__boxList\">\n                <li class=\"p-personalId__boxItem\">Hong Kong Identity Card<\/li>\n        <li class=\"p-personalId__boxItem\">Passport<\/li>\n              <\/ul>\n    <\/div>\n    <ul class=\"p-personalId__notesList\">\n      <li class=\"p-personalId__notesItem--red\">Only one of the above forms of identification is required.<\/li>\n      <li class=\"p-personalId__notesItem--red\">We can not buy items from customers under the age of 18 years old.<\/li>\n      <li class=\"p-personalId__notesItem u-onlyPc\">We do not accept identification documents that are expired or out-of-date.<\/li>\n      <li class=\"p-personalId__notesItem u-onlyPc\">Corporate customers follow the same selling process as individual customers. No additional documentation is required.<\/li>\n    <\/ul>\n    <a href=\"\/faq\/\" class=\"p-personalId__btn\">Visit our FAQ section for more information<\/a>\n  <\/div><!-- \/.p-personalId__body -->\n<\/div><\/div>\n\n<div class=\"lazyblock-brandlist-Z8Sycc wp-block-lazyblock-brandlist\"><section class=\"p-brandModels u-mx-10Sp\">\n  <h2 class=\"p-brandModels__title\">\n    Other Popular Brands  <\/h2>\n  <div class=\"p-brandModels__content\">\n    <ul class=\"p-brandModels__list\">\n            <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/chanel\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_chanel.webp' alt='Chanel' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Chanel<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/balenciaga\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_balenciaga.webp' alt='Balenciaga' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Balenciaga<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/franckmuller\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_franckmuller.webp' alt='Franck Muller' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Franck Muller<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/loewe\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_loewe.webp' alt='Loewe' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Loewe<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/dior\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_dior.webp' alt='Dior' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Dior<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/chopard\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_chopard.webp' alt='Chopard' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Chopard<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/piaget\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_piaget.webp' alt='Piaget' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Piaget<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/harrywinston\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_harrywinston.webp' alt='Harry Winston' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Harry Winston<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/fendi\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_fendi.webp' alt='Fendi' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Fendi<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/celine\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_celine.webp' alt='Celine' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Celine<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/vacheron-constantin\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_vacheron-constantin.webp' alt='Vacheron Constantin' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Vacheron Constantin<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/prada\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_prada.webp' alt='Prada' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Prada<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/chrome-hearts\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_chrome-hearts.webp' alt='Chrome Hearts' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Chrome Hearts<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/gucci\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_gucci.webp' alt='Gucci' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Gucci<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/tiffany\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_tiffany.webp' alt='Tiffany &#038; Co.' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Tiffany &#038; Co.<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/bulgari\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_bulgari.webp' alt='Bulgari' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Bulgari<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/cartier\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_cartier.webp' alt='Cartier' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Cartier<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/hermes\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_hermes.webp' alt='Herm\u00e8s' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Herm\u00e8s<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/louis-vuitton\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_louis-vuitton.webp' alt='Louis Vuitton' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Louis Vuitton<\/span><\/p>\n      <\/a><\/li>    <\/ul>\n  <\/div>\n    <p class=\"p-brandModels__btnArea\">\n    <a class=\"p-brandModels__btn\" href=\"\/en\/bags\/\">&gt; Brand Bag Page<\/a>\n  <\/p>\n  <p class=\"p-brandModels__btnArea\">\n    <a class=\"p-brandModels__btn\" href=\"\/en\/item-list\/\">&gt; Brand List Page<\/a>\n  <\/p>\n<\/section><\/div>\n\n<div class=\"lazyblock-brandlist-Z2vEVC9 wp-block-lazyblock-brandlist\"><section class=\"p-brandModels u-mx-10Sp\">\n  <h2 class=\"p-brandModels__title\">\n    Other Popular Brands  <\/h2>\n  <div class=\"p-brandModels__content\">\n    <ul class=\"p-brandModels__list\">\n            <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/chanel\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_chanel.webp' alt='Chanel' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Chanel<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/balenciaga\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_balenciaga.webp' alt='Balenciaga' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Balenciaga<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/franckmuller\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_franckmuller.webp' alt='Franck Muller' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Franck Muller<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/loewe\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_loewe.webp' alt='Loewe' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Loewe<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/dior\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_dior.webp' alt='Dior' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Dior<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/chopard\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_chopard.webp' alt='Chopard' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Chopard<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/piaget\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_piaget.webp' alt='Piaget' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Piaget<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/harrywinston\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_harrywinston.webp' alt='Harry Winston' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Harry Winston<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/fendi\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_fendi.webp' alt='Fendi' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Fendi<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/celine\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_celine.webp' alt='Celine' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Celine<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/vacheron-constantin\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_vacheron-constantin.webp' alt='Vacheron Constantin' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Vacheron Constantin<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/prada\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_prada.webp' alt='Prada' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Prada<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/chrome-hearts\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_chrome-hearts.webp' alt='Chrome Hearts' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Chrome Hearts<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/gucci\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_gucci.webp' alt='Gucci' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Gucci<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/tiffany\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_tiffany.webp' alt='Tiffany &#038; Co.' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Tiffany &#038; Co.<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/bulgari\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_bulgari.webp' alt='Bulgari' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Bulgari<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/cartier\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_cartier.webp' alt='Cartier' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Cartier<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/hermes\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_hermes.webp' alt='Herm\u00e8s' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Herm\u00e8s<\/span><\/p>\n      <\/a><\/li>      <li class='p-brandModels__listItem'><a class='p-brandModels__listLink' href='https:\/\/sell-hk.allu-official.com\/en\/louis-vuitton\/'>\n        <p class='p-brandModels__listImgArea'><img class=\"p-brandModels__listImg\" src='https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/brand\/material\/brand_louis-vuitton.webp' alt='Louis Vuitton' width=\"155\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n        <p class='p-brandModels__listName'><span class='p-brandModels__listNameInner'>Louis Vuitton<\/span><\/p>\n      <\/a><\/li>    <\/ul>\n  <\/div>\n    <p class=\"p-brandModels__btnArea\">\n    <a class=\"p-brandModels__btn\" href=\"\/en\/bags\/\">&gt; Brand Bag Page<\/a>\n  <\/p>\n  <p class=\"p-brandModels__btnArea\">\n    <a class=\"p-brandModels__btn\" href=\"\/en\/item-list\/\">&gt; Brand List Page<\/a>\n  <\/p>\n<\/section><\/div>\n\n<div class=\"lazyblock-cta-Z1sxjXb wp-block-lazyblock-cta\"><div class=\"p-cta\">\n  <div class=\"p-cta__inner\">\n    <div class=\"p-cta__title\">\n            <p class=\"p-cta__titleText\">How to Sell Luxury Goods at ALLU<\/p>\n    <\/div>\n    <ul class=\"p-cta__list\">\n      <li class=\"p-cta__listItem--shop\">\n        <a href=\"\/en\/store-service\/\" class=\"p-cta__listLink--shop\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Sell to Store\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_store.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Sell at Store<\/p>\n            <p class=\"p-cta__listLinkSub\">The quickest way to get cash<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n      <\/li>\n                  <li class=\"p-cta__listItem--whats\">\n                <a target=\"_blank\" href=\"https:\/\/api.whatsapp.com\/send?phone=85298898591&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" class=\"p-cta__listLink--whats\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Chat on WhatsApp\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_sns.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Chat on WhatsApp<\/p>\n            <p class=\"p-cta__listLinkSub\">Contact Us<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n              <\/li>\n    <\/ul>\n  <\/div>\n<\/div><\/div>\n\n<div class=\"lazyblock-qanda-Z2lBcbT wp-block-lazyblock-qanda\">\n\n<section class=\"p-qanda\" id=\"brand-qanda\">\n  <div class=\"p-qanda__inner\">\n    <h2 class=\"p-qanda__title\">ALLU Frequently Asked Questions<\/h2>    <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Can I sell items that are broken or in poor condition?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes, we can often purchase such items.<br \/>\n<br \/>\n      For example:<br \/>\n<br \/>\n      Items that are worn or old<br \/>\n      Items that are stained, dirty, or mouldy<br \/>\n      Items that have wear and tear or discoloured<br \/>\n      Items that are sticky or ripped<br \/>\n      Items with broken handles<br \/>\n<br \/>\n      If you ever were refused by other stores when trying to sell your item for reasons such as the above, please visit us at ALLU.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Do items with the original box or accessories sell for more?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes. If you still have the box or accessories, you are more likely to be offered a higher price if you bring them. If the item is in good condition, you can still sell your items for high prices even if the above accessories are not included.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">I received a higher selling price at another store.<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        We will do our best to meet your expectations, so please let us know how much the other company&#8217;s evaluation was.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Can I sell items at or above the retail price?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        While some items can be sold at or above retail price, the value of most branded items tends to decrease over time. In many cases, if you no longer use the item, selling it as soon as possible is better to ensure a higher selling price.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Do selling prices vary from store to store?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        No. All of our stores use the same standards for evaluation.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Do I need to make an appointment?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes. We ask that customers make an appointment via WhatsApp first so we can make sure that the appraisal can go smoothly.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">How long does it take for an appraisal at the store?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        We estimate 10 to 15 minutes for a single item. It depends on the item and the quantity, so please ask our staff when you visit.      <\/div>\n    <\/div>\n      <\/div>\n<\/section>\n\n<script type=\"application\/ld+json\">\n  {\n      \"@context\": \"https:\/\/schema.org\",\n      \"@id\":\"#FAQContents\",\n      \"@type\": \"FAQPage\",\n      \"mainEntity\": [\n                {\n          \"@type\": \"Question\",\n          \"name\": \"Can I sell items that are broken or in poor condition?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes, we can often purchase such items.      For example:      Items that are worn or old      Items that are stained, dirty, or mouldy      Items that have wear and tear or discoloured      Items that are sticky or ripped      Items with broken handles      If you ever were refused by other stores when trying to sell your item for reasons such as the above, please visit us at ALLU.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Do items with the original box or accessories sell for more?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes. If you still have the box or accessories, you are more likely to be offered a higher price if you bring them. If the item is in good condition, you can still sell your items for high prices even if the above accessories are not included.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"I received a higher selling price at another store.\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"We will do our best to meet your expectations, so please let us know how much the other company&#039;s evaluation was.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Can I sell items at or above the retail price?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"While some items can be sold at or above retail price, the value of most branded items tends to decrease over time. In many cases, if you no longer use the item, selling it as soon as possible is better to ensure a higher selling price.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Do selling prices vary from store to store?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"No. All of our stores use the same standards for evaluation.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Do I need to make an appointment?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes. We ask that customers make an appointment via WhatsApp first so we can make sure that the appraisal can go smoothly.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"How long does it take for an appraisal at the store?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"We estimate 10 to 15 minutes for a single item. It depends on the item and the quantity, so please ask our staff when you visit.\"\n          }\n        }              ]\n  }\n<\/script>\n<\/div>","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/brand\/1968"}],"collection":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/brand"}],"about":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/types\/brand"}],"version-history":[{"count":8,"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/brand\/1968\/revisions"}],"predecessor-version":[{"id":8482,"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/brand\/1968\/revisions\/8482"}],"wp:attachment":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/media?parent=1968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}