{"id":1922,"date":"2023-08-08T13:26:44","date_gmt":"2023-08-08T04:26:44","guid":{"rendered":"https:\/\/sell-hk.allu-official.com\/jewelry\/damiani\/"},"modified":"2023-09-03T12:15:43","modified_gmt":"2023-09-03T03:15:43","slug":"damiani","status":"publish","type":"jewelry","link":"https:\/\/sell-hk.allu-official.com\/en\/jewelry\/damiani\/","title":{"rendered":"Damiani"},"content":{"rendered":"<div class=\"lazyblock-visual-imgarea-ZwINqU wp-block-lazyblock-visual-imgarea\"><section class=\"p-visual\">\n    <div class=\"p-visual__imageArea\">\n      <div class=\"p-visual__imageContents\">\n          <h1 class=\"p-visual__heading\">\n        <span class=\"p-visual__headingLead\">Competitive Valuation!<\/span>\n        <span class=\"p-visual__headingTitle\">Sell Your Damiani Jewellery at ALLU Today!<\/span>\n      <\/h1>\n          <div class=\"p-visual__cta\">\n                        <div class=\"p-visual__ctaItem\">\n                              <a href=\"https:\/\/api.whatsapp.com\/send?phone=85253630726&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" target=\"_blank\" class=\"p-visual__ctaButton--whatsapp\" rel=\"noopener\">Get a Quote<\/a>\n                          <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"p-visual__imageBlock\">\n        <div class=\"p-visual__image\">\n            <!-- GLOBAL_VJ_MARKTING-674 -->\n                                            <!-- PC\uff1a\u5e38\u306b\u30c7\u30d5\u30a9\u30eb\u30c8 -->\n                <img decoding=\"async\" class=\"u-onlyPc\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/material\/jewelry_damiani.png\" alt=\"Damiani\" width=\"640\" height=\"500\">\n                <!-- SP\uff1a\u767b\u9332\u753b\u50cf\u304c\u3042\u308c\u3070\u305d\u308c\u3001\u306a\u3051\u308c\u3070\u30c7\u30d5\u30a9\u30eb\u30c8 -->\n                <img decoding=\"async\" class=\"u-onlySp\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/material\/jewelry_damiani.png\" alt=\"Damiani\" width=\"640\" height=\"500\">\n                    <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n<div class=\"p-introduction\">\n  <p class=\"p-introduction__text\">DAMIANI is considered the pinnacle of Italian jewellery. At ALLU, we strive to provide accurate valuations and the most competitive prices for your DAMIANI items.<\/p>\n<\/div><\/div>\n\n\n<!--more-->\n\n\n<div class=\"lazyblock-abouttext-Z181hFJ wp-block-lazyblock-abouttext\"><section class=\"p-aboutText\">\n  <h2 class=\"p-aboutText__title--jewelry u-mx-10Sp\">Sell Your Damiani Jewellery at ALLU<\/h2>\n  <p class=\"p-aboutText__text\">Damiani gained its current prominence by channelling its efforts into utilising high-quality diamonds, and even the most minuscule diamonds used in its pav\u00e9 are tested against the brand&#8217;s strict standards. Since the brand was founded in 1976, it has won 22 separate awards at the Diamond International Awards, further strengthening its reputation as a reliable source of high-class diamonds. The high-end accessories crafted by Damiani&#8217;s seasoned artisans have won the loyalty of fashion gurus in many major cities around the globe, including Milan, New York, Los Angeles, Paris and Tokyo.<br \/>\n<br \/>\nIn recent years, Damiani has opened stores in Hong Kong and Macau and gained even more attention. However, its biggest boast may be that Sophia Loren and Brad Pitt, both celebrated actors worldwide, have helped spread Damiani&#8217;s popularity internationally by supporting and frequently wearing pieces by the brand. In particular, Brad Pitt fell in love with Damiani&#8217;s style and commissioned both his engagement and wedding ring from Damiani in 2000. &#8216;D.Side&#8217;, a collaboration between Pitt and Damiani, sports the titular D, which both stands for Damiani and their area of expertise, diamonds. This bridal ring garnered attention all over the globe with its style of double rings joined by a single diamond and was designed with the theme of a vow of love and &#8216;the decision of a lifetime.&#8217; Damiani&#8217;s pieces are loved by couples worldwide, which is no surprise given the brand&#8217;s association with love, dedication, reason, passion, beauty and harmony. <br \/>\n<br \/>\nAt ALLU, we offer the most competitive prices that can be expected from a high-end jewellery brand. If you want to sell your Damiani jewellery, please take advantage of our services and visit us for a thorough assessment by our expert staff. <\/p>\n<\/section><\/div>\n\n<div class=\"lazyblock-brandrecord-ZYAUIR wp-block-lazyblock-brandrecord\"><section class=\"p-brandRecord\">\n  <h2 class=\"p-brandRecord__title\">Damiani Market Price Examples<\/h2>\n\n  <ul class=\"p-brandRecord__list\">\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2987252.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">11995.64<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,041<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,586<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2996620.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Bracelet 750(PG) M A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">15294.12<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Bracelet 750(PG) M A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">805<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,771<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A3005483.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) XXS AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10588.24<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) XXS AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">407<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,401<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2972256.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">18808.29<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,146<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,945<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2952487.jpg\" alt=\"Damiani Diamond Ring 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2094.19<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Diamond Ring 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">397<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,369<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/AP077571.jpg\" alt=\"Damiani Luce Diamond Bracelet 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8734.49<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Luce Diamond Bracelet 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">700<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,412<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2320476.jpg\" alt=\"Damiani Luce Sapphire Bracelet 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">20693.07<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Luce Sapphire Bracelet 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,013<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,488<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/VP008552.jpg\" alt=\"Damiani Frammenti Cross Ruby Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3485.15<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Frammenti Cross Ruby Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">653<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,249<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2924355.jpg\" alt=\"Damiani Crystal Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3430.69<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Crystal Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">435<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,499<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2864848.jpg\" alt=\"Damiani Juliette Garnet Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">14257.23<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Juliette Garnet Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2,112<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">7,270<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2915657.jpg\" alt=\"Damiani Luce Sapphire Bracelet 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">21492.99<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Luce Sapphire Bracelet 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,032<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,553<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2901577.jpg\" alt=\"Damiani D Icon Diamond Earrings 750(PG\u00d7WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4515.97<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon Diamond Earrings 750(PG\u00d7WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,307<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,499<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2875097.jpg\" alt=\"Damiani Crystal Line Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">5592.27<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Crystal Line Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">682<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,347<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2239965.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">20691.41<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,136<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,912<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2097670.jpg\" alt=\"Damiani D Side Malachite Diamond Necklace 750(YG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">17895.27<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Side Malachite Diamond Necklace 750(YG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2,926<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">10,074<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2854946.jpg\" alt=\"Damiani D race Diamond Necklace 750 (WG) x Ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10055.87<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D race Diamond Necklace 750 (WG) x Ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">2,841<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">9,781<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2739671.jpg\" alt=\"Damiani Mini Simboli Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2533.27<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Mini Simboli Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">236<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">815<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/YZ061751.jpg\" alt=\"Damiani Luce Black diamond Diamond Bracelet 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8911.39<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Luce Black diamond Diamond Bracelet 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">852<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,934<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/YZ061749.jpg\" alt=\"Damiani Ros\u00e9 Diamond Necklace 750(PG\u00d7WG) A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8478.93<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Ros\u00e9 Diamond Necklace 750(PG\u00d7WG) A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,345<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,629<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2758655.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(WG) A rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">40403.52<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(WG) A rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,202<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,140<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2764983.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">38696.33<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,165<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,010<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2750885.jpg\" alt=\"Damiani D Icon 1P Diamond Ring 750 (WG) x Ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2303.66<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon 1P Diamond Ring 750 (WG) x Ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">880<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,032<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2564514.jpg\" alt=\"Damiani Mystery Cross Black diamond Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4592.90<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Mystery Cross Black diamond Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">776<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,673<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2560591.jpg\" alt=\"Damiani Belle \u00c9poque Square Ruby Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3559.50<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Square Ruby Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">426<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,467<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/XB021981.jpg\" alt=\"Damiani Margherita Amethyst Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">12183.54<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Margherita Amethyst Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">577<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,988<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2682810.jpg\" alt=\"Damiani D Icon 1P Diamond Necklace 750 (WG) x Ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3124.33<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon 1P Diamond Necklace 750 (WG) x Ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">710<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,445<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2676010.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">19203.49<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,382<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,760<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2621168.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">14612.11<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">738<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,543<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/BW020175.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">17077.09<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,108<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,814<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2559898.jpg\" alt=\"Damiani Ruby Diamond Brooch 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8909.29<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Ruby Diamond Brooch 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">577<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,988<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/XB021784.jpg\" alt=\"Damiani Margherita Amethyst Bracelet 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10097.19<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Margherita Amethyst Bracelet 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">435<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,499<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2546247.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">20194.38<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,127<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,879<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2478009.jpg\" alt=\"Damiani Bocciolo Diamond Ring Pt950 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3875.84<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Bocciolo Diamond Ring Pt950 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">321<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,043<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2414471.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">15027.32<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">682<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,347<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2405400.jpg\" alt=\"Damiani Belle \u00c9poque hearts Diamond Necklace 750(PG\u00d7WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">6436.17<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque hearts Diamond Necklace 750(PG\u00d7WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">615<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,119<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2326540.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">19411.76<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,136<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,912<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2343857.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">7047.52<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">947<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,260<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2302298.jpg\" alt=\"Damiani Eden Diamond Necklace 750 (PG) x Ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">7062.60<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Eden Diamond Necklace 750 (PG) x Ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">663<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,282<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2269886.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">38255.75<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,165<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,010<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2312575.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(WG) L AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">44141.25<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(WG) L AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,401<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,825<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2291160.jpg\" alt=\"Damiani Damianissima Diamond Necklace 750(PG\u00d7WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8847.18<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Damianissima Diamond Necklace 750(PG\u00d7WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,354<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,662<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/BW019253.jpg\" alt=\"Damiani D Icon 1P Diamond Ring 750 (PG) x Ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2191.71<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon 1P Diamond Ring 750 (PG) x Ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">682<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,347<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2267073.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">23655.91<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,117<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,847<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2265866.jpg\" alt=\"Damiani Mystery Cross Black diamond Diamond Necklace 750 AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3884.43<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Mystery Cross Black diamond Diamond Necklace 750 AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">767<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,640<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2256062.jpg\" alt=\"Damiani Mini Simboli Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2589.62<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Mini Simboli Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">151<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">521<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2226655.jpg\" alt=\"Damiani D Icon Diamond Necklace 750(PG\u00d7WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">8337.85<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon Diamond Necklace 750(PG\u00d7WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">710<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,445<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2227730.jpg\" alt=\"Damiani Notte Di San Lorenzo Diamond Bracelet 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">26858.38<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Notte Di San Lorenzo Diamond Bracelet 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">909<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,129<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2177208.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">9105.96<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">918<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,162<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/XB019535.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(YG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">17604.86<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(YG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">719<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,477<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2175477.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">20640.18<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">824<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,836<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2162436.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">19577.31<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">691<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,380<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2160992.jpg\" alt=\"Damiani D race white agate Diamond Bracelet 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3731.92<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D race white agate Diamond Bracelet 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">909<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,129<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2158071.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">13954.77<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">454<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,564<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2143910.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">17391.30<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">691<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,380<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2097667.jpg\" alt=\"Damiani Sophia Loren Diamond Earrings 750(PG\u00d7WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">18911.17<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Sophia Loren Diamond Earrings 750(PG\u00d7WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,439<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,955<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2119974.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">19943.34<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">710<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,445<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/TW019809.jpg\" alt=\"Damiani Belle \u00c9poque Crown Diamond Necklace 750(YG) M AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">47771.43<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Crown Diamond Necklace 750(YG) M AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,240<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,271<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2110400.jpg\" alt=\"Damiani Mini Symbol Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4844.72<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Mini Symbol Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">303<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,043<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2093191.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10784.31<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">416<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,434<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2091774.jpg\" alt=\"Damiani Academia Diamond Necklace 750(PG\u00d7WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">6192.69<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Academia Diamond Necklace 750(PG\u00d7WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,392<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,792<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2075417.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">20777.78<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,127<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,879<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2062146.jpg\" alt=\"Damiani Belle \u00c9poque Diamond Ring 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">14609.85<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Diamond Ring 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">634<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,184<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2054182.jpg\" alt=\"Damiani D Side 10P Diamond Ring 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2382.01<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Side 10P Diamond Ring 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">511<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,760<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/HX045688.jpg\" alt=\"Damiani Crystal Diamond Ring 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">5543.11<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Crystal Diamond Ring 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">492<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,695<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2038578.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Sapphire Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">28947.37<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Sapphire Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,098<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,782<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2043375.jpg\" alt=\"Damiani D Side 10P Diamond Ring 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">3134.08<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Side 10P Diamond Ring 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">644<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,217<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/HX045677.jpg\" alt=\"Damiani Crystal Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4608.94<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Crystal Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">786<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,706<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2027302.jpg\" alt=\"Damiani Abbraccio Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">7449.21<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Abbraccio Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">454<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,564<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2003639.jpg\" alt=\"Damiani Eden Diamond Earing piercing 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">22850.55<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Eden Diamond Earing piercing 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,382<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">4,760<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2017208.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">18407.39<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">682<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,347<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2003637.jpg\" alt=\"Damiani Eden Diamond Bracelet 750(WG) M AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">33641.08<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Eden Diamond Bracelet 750(WG) M AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,686<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">5,803<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2010433.jpg\" alt=\"Damiani Luce Diamond Bracelet 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">19009.22<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Luce Diamond Bracelet 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">795<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,738<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A2007951.jpg\" alt=\"Damiani Belle \u00c9poque Cross Sapphire Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">19009.22<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Sapphire Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">1,117<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,847<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A1994640.jpg\" alt=\"Damiani Belle \u00c9poque Diamond Earrings 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">11346.70<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Diamond Earrings 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">350<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,206<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A1997559.jpg\" alt=\"Damiani D Icon 1P Diamond Earrings 750 (PG x WG) x ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4601.72<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon 1P Diamond Earrings 750 (PG x WG) x ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A1999381.jpg\" alt=\"Damiani Damianissima Ring 750(PG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2017.19<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Damianissima Ring 750(PG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">284<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">978<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A1975428.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(YG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">16942.38<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(YG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">710<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">2,445<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/WU017593.jpg\" alt=\"Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">10103.33<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Belle \u00c9poque Cross Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">454<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,564<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/A1982790.jpg\" alt=\"Damiani Abbraccio Diamond Necklace 750(WG) AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">4546.50<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani Abbraccio Diamond Necklace 750(WG) AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">473<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">1,630<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n    <li class=\"p-brandRecord__item js-brandRecordItem\">\n      <div class=\"p-brandRecord__itemImageArea\">\n        <img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/static.sell-hk.allu-official.com\/EO005507.jpg\" alt=\"Damiani D Icon 1P Diamond Ring 750 (PG) x Ceramic AB rank\" width=\"500\" height=\"500\">\n      <\/div>\n      <div class=\"p-brandRecord__itemPrice\">\n        <span>$<\/span>\n        <span class=\"p-brandRecord__itemPriceNum\">2462.69<\/span>\n        <span><\/span>\n      <\/div>\n      <p class=\"p-brandRecord__itemText\">Damiani D Icon 1P Diamond Ring 750 (PG) x Ceramic AB rank<\/p>\n      <div class=\"p-brandRecord__info\">\n          <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\">\n            <img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconCo2\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-co2.png\" width=\"93\" height=\"auto\" alt=\"CO2\">\n          <\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-tree.svg\" class=\"p-brandRecord__iconTree\" alt=\"Tree\">\n            <p class=\"p-brandRecord__infoBottomText\">(Cedar Trees) x <span class=\"p-brandRecord__infoBottomTextNum\">880<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n            <div class=\"p-brandRecord__infoItem\">\n          <p class=\"p-brandRecord__infoTop\"><img decoding=\"async\" loading=\"lazy\" class=\"p-brandRecord__iconWater\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-water.png\" width=\"56\" height=\"auto\" alt=\"Water\"><\/p>\n          <div class=\"p-brandRecord__infoBottom\">\n            <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon-bath.svg\" class=\"p-brandRecord__iconBath\" alt=\"Bath\">\n            <p class=\"p-brandRecord__infoBottomText\">(Bath Tubs) x <span class=\"p-brandRecord__infoBottomTextNum\">3,032<\/span><\/p>\n          <\/div>\n        <\/div><!--\/.p-brandRecord__infoItem-->\n        <\/div>\n    <\/li>\n  <\/ul>\n    <div class=\"p-brandRecord__more js-brandRecordMore\">View More<\/div>\n  <p class=\"p-brandRecord__notes\">*The above prices are for reference only (tax included) and do not guarantee the actual selling price. The actual price may vary depending on the item&#039;s condition, the inclusion of accessories, the date of manufacture, market fluctuations, and stock availability.<\/p>\n    \n<\/section>\n<\/div>\n\n\n\n<div class=\"lazyblock-google-CqpSc wp-block-lazyblock-google\"><section class=\"p-userComment \" id=\"customer-review\">\n  <h2 class=\"p-userComment__title\">\n  Selling Damiani at ALLU: Google Reviews<\/h2>\n\n  <!-- WP Google Review Slider -->\n  <div class=\"p-googleReviewSlider\">\n    <div class=\"p-googleReviewSlider__container\" data-loaded=\"false\">\n    <style>#wprev-slider-1 .wprev_preview_bradius_T1 {border-radius: 0px;}#wprev-slider-1 .wprev_preview_bg1_T1::after{ border-top: 30px solid ; }<\/style><style><\/style><div class=\"wprev-no-slider revnotsameheight\" id=\"wprev-slider-1\">\t\t<div class=\"wprevpro_t1_outer_div w3_wprs-row-padding\">\r\n\t\t\t\t<div class=\"wprevpro_t1_DIV_1 w3_wprs-col l12\">\r\n\t\t\t<div class=\"indrevdiv wprevpro_t1_DIV_2 wprev_preview_bg1_T1 wprev_preview_tcolor1_T1 wprev_preview_bradius_T1\">\r\n\t\t\t\t<p class=\"wprevpro_t1_P_3 wprev_preview_tcolor1_T1\">\r\n\t\t\t\t\t<span class=\"wprevpro_star_imgs_T1\"><span class=\"starloc1 wprevpro_star_imgs wprevpro_star_imgsloc1\"><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><\/span><\/span>First class service\ud83d\udc4d\ud83c\udffb\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><span class=\"wprevpro_t1_A_8\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXuS_jO_pg3d4bRLO6-8XOw9E_-X91FJ9x9Z9Vjw76JgUWKW6nM=s128-c0x00000000-cc-rp-mo?sz=100\" alt=\"Jenny Avatar\" class=\"wprevpro_t1_IMG_4\" loading=\"lazy\" \/><\/span> <span class=\"wprevpro_t1_SPAN_5 wprev_preview_tcolor2_T1\">Jenny<br\/><span class=\"wprev_showdate_T1\"><\/span> <\/span>\r\n\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"wprevpro_t1_outer_div w3_wprs-row-padding\">\r\n\t\t\t\t<div class=\"wprevpro_t1_DIV_1 w3_wprs-col l12\">\r\n\t\t\t<div class=\"indrevdiv wprevpro_t1_DIV_2 wprev_preview_bg1_T1 wprev_preview_tcolor1_T1 wprev_preview_bradius_T1\">\r\n\t\t\t\t<p class=\"wprevpro_t1_P_3 wprev_preview_tcolor1_T1\">\r\n\t\t\t\t\t<span class=\"wprevpro_star_imgs_T1\"><span class=\"starloc1 wprevpro_star_imgs wprevpro_star_imgsloc1\"><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><\/span><\/span>Nice\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><span class=\"wprevpro_t1_A_8\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLHLr5WfIYcP_PvxXnIu5skiZW8Bv2DkaVJ4K7zTLR48S0nwqM=s128-c0x00000000-cc-rp-mo?sz=100\" alt=\"Flora Hsu Avatar\" class=\"wprevpro_t1_IMG_4\" loading=\"lazy\" \/><\/span> <span class=\"wprevpro_t1_SPAN_5 wprev_preview_tcolor2_T1\">Flora H.<br\/><span class=\"wprev_showdate_T1\"><\/span> <\/span>\r\n\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"wprevpro_t1_outer_div w3_wprs-row-padding\">\r\n\t\t\t\t<div class=\"wprevpro_t1_DIV_1 w3_wprs-col l12\">\r\n\t\t\t<div class=\"indrevdiv wprevpro_t1_DIV_2 wprev_preview_bg1_T1 wprev_preview_tcolor1_T1 wprev_preview_bradius_T1\">\r\n\t\t\t\t<p class=\"wprevpro_t1_P_3 wprev_preview_tcolor1_T1\">\r\n\t\t\t\t\t<span class=\"wprevpro_star_imgs_T1\"><span class=\"starloc1 wprevpro_star_imgs wprevpro_star_imgsloc1\"><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><span class=\"svgicons svg-wprsp-star\"><\/span><\/span><\/span>Decent and swift service! Recommend!\t\t\t\t<\/p>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/div><span class=\"wprevpro_t1_A_8\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIs-AtxM-goZ1HL7XGVh0NUHmJCQ-ZovSou524f9EQZ7PCu3g=s128-c0x00000000-cc-rp-mo?sz=100\" alt=\"Meave Lai Avatar\" class=\"wprevpro_t1_IMG_4\" loading=\"lazy\" \/><\/span> <span class=\"wprevpro_t1_SPAN_5 wprev_preview_tcolor2_T1\">Meave L.<br\/><span class=\"wprev_showdate_T1\"><\/span> <\/span>\r\n\t\t<\/div>\r\n\t\t<\/div>\r\n<\/div>\r\n    <\/div>\n  <\/div>\n<\/section><\/div>\n\n<div class=\"lazyblock-cta-1URWzt wp-block-lazyblock-cta\"><div class=\"p-cta\">\n  <div class=\"p-cta__inner\">\n    <div class=\"p-cta__title\">\n            <p class=\"p-cta__titleText\">\n                How to Sell Luxury Goods at ALLU              <\/p>\n    <\/div>\n    <ul class=\"p-cta__list\">\n      <li class=\"p-cta__listItem--shop\">\n        <a href=\"\/en\/store-service\/\" class=\"p-cta__listLink--shop\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Sell to Store\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_store.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">\n                        Sell at Store                        <\/p>\n            <p class=\"p-cta__listLinkSub\">\n                        The quickest way to get cash                        <\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n      <\/li>\n                  <li class=\"p-cta__listItem--whats\">\n                <a target=\"_blank\" href=\"https:\/\/api.whatsapp.com\/send?phone=85253630726&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" class=\"p-cta__listLink--whats\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Chat on WhatsApp\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_sns.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Chat on WhatsApp<\/p>\n            <p class=\"p-cta__listLinkSub\">Contact Us<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n              <\/li>\n    <\/ul>\n  <\/div>\n<\/div><\/div>\n\n\n\n<div class=\"lazyblock-purchasepriceup-2mgrci wp-block-lazyblock-purchasepriceup\"><section class=\"p-purchasePriceUp\">\n  <h2 class=\"c-headingMain\">Increase the Selling Price of Your Jewellery!<\/h2>\n  <div class=\"p-purchasePriceUp__wrapper\">\n    <ul class=\"p-purchasePriceUp__list\">\n      <li class=\"p-purchasePriceUp__listItem\">\n        <div class=\"p-purchasePriceUp__listInner\">\n          <p class=\"p-purchasePriceUp__text\">\n            <span class=\"p-purchasePriceUp__textlabel\">Large diamonds of 1 carat or more are rare and can lead to higher selling prices.<\/span><\/p>\n        <\/div>\n      <\/li>\n      <li class=\"p-purchasePriceUp__listItem\">\n        <div class=\"p-purchasePriceUp__listInner\">\n          <p class=\"p-purchasePriceUp__text\">\n            <span class=\"p-purchasePriceUp__textlabel\">Famous brands and luxurious designs can lead to higher selling prices.<\/span><\/p>\n        <\/div>\n      <\/li>\n      <li class=\"p-purchasePriceUp__listItem\">\n        <div class=\"p-purchasePriceUp__listInner\">\n          <p class=\"p-purchasePriceUp__text\">\n            <span class=\"p-purchasePriceUp__textlabel\">Coloured diamonds are also rare and can lead to higher selling prices.<\/span><\/p>\n        <\/div>\n      <\/li>\n      <li class=\"p-purchasePriceUp__listItem\">\n        <div class=\"p-purchasePriceUp__listInner\">\n          <p class=\"p-purchasePriceUp__text\">\n            <span class=\"p-purchasePriceUp__textlabel\">Diamonds of VS grade or above are rare and can lead to higher selling prices.<\/span><\/p>\n        <\/div>\n      <\/li>\n    <\/ul>\n  <\/div>\n<\/section><\/div>\n\n<div class=\"lazyblock-purchaseitems-Z2iw03M wp-block-lazyblock-purchaseitems\"><section class=\"p-purchaseItems\">\n  <h2 class=\"c-headingMain\">What We Buy at ALLU<\/h2>\n<!-- GLOBAL_VJ_MARKTING-672 -->\n    <div class=\"u-onlyPc\">\n        <ul class=\"p-purchaseItems__list\">\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_gold.webp\" alt=\"Gold and Precious Metals\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Gold and Precious Metals<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_watch.webp\" alt=\"Watches\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Watches<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_bag.webp\" alt=\"Brand Bags\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Brand Bags<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_wallet.webp\" alt=\"Brand Wallets\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Brand Wallets<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_jewelry.webp\" alt=\"Jewellery\" width=\"107\" height=\"107\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Jewellery<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_accessory.webp\" alt=\"Accessories\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/><\/div><span class=\"p-purchaseItems__listLabel\">Accessories<\/span><\/li>\n            <li class=\"p-purchaseItems__listItem\"><div class=\"p-purchaseItems__listImage\"><img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/purchaseItems\/purchase_antique.webp\" alt=\"Antiques\" width=\"103\" height=\"104\" loading=\"lazy\" decoding=\"async\" \/>\n            <\/div><span class=\"p-purchaseItems__listLabel\">Antiques<\/span><\/li>\n        <\/ul>\n        <h3 class=\"p-purchaseItems__subtitle\"><span class=\"p-purchaseItems__subtitleInner\">\u25a0 Items You Can Sell<\/span><\/h3>\n        <p class=\"p-purchaseItems__text\">Bags, pouches, tote bags, business bags, boston bags, clutches, travel bags, shoulder bags, wallets, card cases, passport holders, key cases, wristwatches, mules, sandals, oxfords, pumps, boots, pair rings, rings, necklaces, pendants, piercings, earrings, brooches, bracelets, gloves, belts, pens, wrist bands, anklets, accessories, eyewear, hats and caps, handkerchiefs, neckties, stoles, scarves, bangles, etc.<\/p>\n    <\/div>\n\n    <section class=\"p-topCategoryBox u-onlySp\">\n    <div class=\"p-topCategoryBox__inner\">\n        <div class=\"p-topCategoryBox__container\">\n        <div class=\"p-topCategoryBox__item\">\n            <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/watches\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_watch.webp\" alt=\"Sell your luxury watches.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">WATCH<br\/><span class=\"p-topCategoryBox__titleSub\">Sell your luxury watches.<\/span><\/h4>\n            <\/a>\n        <\/div>\n        <div class=\"p-topCategoryBox__item\">\n                        <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/gold\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_gold.webp\" alt=\"Sell your gold and precious metals.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">GOLD<br\/><span class=\"p-topCategoryBox__titleSub\">Sell your gold and precious metals.<\/span><\/h4>\n            <\/a>\n                    <\/div>\n        <div class=\"p-topCategoryBox__item\">\n            <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/bags\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_bag.webp\" alt=\"Sell your branded bags and wallets.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">BAGS<br\/><span class=\"p-topCategoryBox__titleSub\">Sell your branded bags and wallets.<\/span><\/h4>\n            <\/a>\n        <\/div>\n        <div class=\"p-topCategoryBox__item\">\n            <a class=\"p-topCategoryBox__itemLink\" href=\"\/en\/jewelry\/\">\n            <img src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/top\/top_category_bg_jewelry.webp\" alt=\"Sell your precious jewellery and gemstones.\" class=\"p-topCategoryBox__itemImg\" width=\"780\" height=\"780\" loading=\"lazy\" decoding=\"async\" \/>\n            <h4 class=\"p-topCategoryBox__title\">JEWELLERY<br\/>\n            <span class=\"p-topCategoryBox__titleSub\">Sell your precious jewellery and gemstones.<\/span><\/h4>\n            <\/a>\n        <\/div>\n        <\/div>\n        <div class=\"p-topCategoryBox__info\">\n        <h3 class=\"p-topCategoryBox__infoTitle\">Luxury Articles We Buy Back<\/h3>\n        <div class=\"p-topCategoryBox__infoBody\">\n            <p class=\"p-topCategoryBox__infoText\">Watches, jewelry, bags, wallets, accessories, clothing, shoes, antiques, gold and precious metals. For other items, please <a class=\"p-topCategoryBox__infoTextRink\"  href=\"https:\/\/api.whatsapp.com\/send?phone=33619259635&#038;text=Bonjour%2C%20je%20souhaite%20prendre%20rendez-vous%20dans%20votre%20bureau%20d%27achat%20pour%20vendre%20mes%20articles%20de%20luxe\" target=\"_blank\" rel=\"noopener\">contact us<\/a> for details.<\/p>\n        <\/div>\n        <\/div>\n    <\/section>\n\n\n<\/section><\/div>\n\n<div class=\"lazyblock-whychoose-PE4lM wp-block-lazyblock-whychoose\">\n<section class=\"p-whyChoose u-mt0\">\n\n            <h2 class=\"p-whyChoose__title\">ALLU Offers Much More than High Selling Prices!<\/h2>\n        <div class=\"p-whyChoose__reason\">\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead--no01\">\n                    <picture class=\"p-whyChoose__reasonNum--no01\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason01_gold.png\" media=\"(min-width: 768px)\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" alt=\"1\" width=\"100\" height=\"130\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason01_gold_sp.png\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle--no01\">Reliable, credible, and trustworthy appraisals<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody--no01\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap--no01\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason01.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" alt=\"Our knowledgeable and experienced experts provide accurate appraisals\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason01_sp.webp\" width=\"235\" height=\"150\" loading=\"lazy\" decoding=\"async\" \/>\n                        <\/picture>\n                        <div class=\"p-whyChoose__reasonBodyImgCaption\">Appraisal and Customer Service Training<\/div>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText--no01\">\n                        Our staff undergo thorough training under the tutelage of specialists in various fields, such as watches and jewellery, that allow us to provide the most accurate, detailed, and credible appraisals. We conduct periodic in-house tests to ensure our employees maintain their expertise and develop new skills. As professionals, we constantly strive to improve our skills to provide the most competitive appraisals.<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead\">\n                    <picture class=\"p-whyChoose__reasonNum\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason02_gold.png\" media=\"(min-width: 768px)\">\n                        <img class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason02_gold_sp.png\" alt=\"2\" width=\"100\" height=\"130\" loading=\"lazy\" decoding=\"async\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle--no02\">Focus on providing high-quality customer service<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap--left\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason02.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason02_sp.webp\" alt=\"Focus on providing high-quality customer service\" loading=\"lazy\" decoding=\"async\">\n                        <\/picture>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText\">We make the selling process as simple as possible, and our staff ensures that our customers understand and are satisfied with each appraisal.<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead\">\n                    <picture class=\"p-whyChoose__reasonNum\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason03_gold.png\" media=\"(min-width: 768px)\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason03_gold_sp.png\" alt=\"3\" width=\"100\" height=\"130\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle\">We purchase a wide variety of items and brands<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap--no03\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason03.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason03_sp.webp\" alt=\"We purchase a wide variety of items and brands\" loading=\"lazy\" decoding=\"async\">\n                        <\/picture>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText--no03\">We cater for an extensive range of items and brands and actively consider items in all conditions, even items our competitors may refuse to buy.<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead\">\n                    <picture class=\"p-whyChoose__reasonNum\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason04_gold.png\" media=\"(min-width: 768px)\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason04_gold_sp.png\" alt=\"4\" width=\"100\" height=\"130\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle\">No selling quantity or price limits<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap--left\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason04.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason04_sp.webp\" alt=\"No selling quantity or price limits\" loading=\"lazy\" decoding=\"async\">\n                        <\/picture>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText\">For customers with large amounts or significantly expensive items, we buy and pay on the day without any limits in quantity or value.<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead\">\n                    <picture class=\"p-whyChoose__reasonNum\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason05_gold.png\" media=\"(min-width: 768px)\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason05_gold_sp.png\" alt=\"5\" width=\"100\" height=\"130\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle\">Quick and easy appraisals<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason05.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason05_sp.webp\" alt=\"Quick and easy appraisals\" loading=\"lazy\" decoding=\"async\">\n                        <\/picture>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText\">Through our expert proficiency and globally vast product data collection, we provide speedy appraisals with minimal waiting time.<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead\">\n                    <picture class=\"p-whyChoose__reasonNum\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason06_gold.png\" media=\"(min-width: 768px)\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason06_gold_sp.png\" alt=\"6\" width=\"100\" height=\"130\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle--no06\">Stress-free and private spaces<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap--left\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason06.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason06_sp.webp\" alt=\"Stress-free and private spaces\" loading=\"lazy\" decoding=\"async\">\n                        <\/picture>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText\">We strive to create the most stress-free selling experience with store spaces designed to ensure comfort and privacy.<\/p>\n                <\/div>\n            <\/div>\n            <div class=\"p-whyChoose__reasonItem\">\n                <div class=\"p-whyChoose__reasonHead\">\n                    <picture class=\"p-whyChoose__reasonNum\">\n                        <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason07_gold.png\" media=\"(min-width: 768px)\">\n                        <img loading=\"lazy\" decoding=\"async\" class=\"p-whyChoose__reasonNumImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/no_reason07_gold_sp.png\" alt=\"7\" width=\"100\" height=\"130\">\n                    <\/picture>\n                    <h3 class=\"p-whyChoose__reasonTitle\">Conveniently located stores<\/h3>\n                <\/div>\n                <div class=\"p-whyChoose__reasonBody\">\n                    <div class=\"p-whyChoose__reasonBodyImgWrap\">\n                        <picture class=\"p-whyChoose__reasonBodyImgArea\">\n                            <source srcset=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason07.webp\" media=\"(min-width: 768px)\">\n                            <img class=\"p-whyChoose__reasonBodyImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/img_reason07_sp.webp\" alt=\"Conveniently located stores\" loading=\"lazy\" decoding=\"async\">\n                        <\/picture>\n                    <\/div>\n                    <p class=\"p-whyChoose__reasonBodyText\">ALLU stores are located in central areas for convenient access. Feel free to stop by while shopping or on the way home.<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n\n    <\/section><\/div>\n\n<div class=\"lazyblock-storeinformation-156DhH wp-block-lazyblock-storeinformation\"><section class=\"p-storeInformation\" id=\"shop-list\"><div class=\"p-storeInformation__inner\"><h2 class=\"p-storeInformation__title\">Shop Information<\/h2><ul class=\"p-storeInformation__list\"><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"Room A2, 16\/F ,Emperor Watch And Jewellery Centre, 8 Russell St, Causeway Bay\" width=\"1280\" height=\"854\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Causeway-Bay_3.jpg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">ALLU HK Causeway Bay Shop<\/h3><address class=\"p-storeInformation__itemAddress\">Room A2, 16\/F ,Emperor Watch And Jewellery Centre, 8 Russell St, Causeway Bay<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/causeway-bay-shop\/\">View ALLU HK Causeway Bay Shop Details<\/a><\/div><\/div><\/li><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"18\/F, Stanley 11, 11 Stanley St, Central, Hong Kong Island, Hong Kong\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Central_1.jpeg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">Central Shop<\/h3><address class=\"p-storeInformation__itemAddress\">18\/F, Stanley 11, 11 Stanley St, Central, Hong Kong Island, Hong Kong<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/central-shop\/\">View Central Shop Details<\/a><\/div><\/div><\/li><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"Room 503-4, 5\/F, Hanford Commercial Centre, 221B-E Nathan Road, Kowloon\" width=\"1280\" height=\"854\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Jordan_2.jpg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">ALLU HK Jordan Shop<\/h3><address class=\"p-storeInformation__itemAddress\">Room 503-4, 5\/F, Hanford Commercial Centre, 221B-E Nathan Road, Kowloon<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/jordan-shop\/\">View ALLU HK Jordan Shop Details<\/a><\/div><\/div><\/li><li class=\"p-storeInformation__item\"><div class=\"p-storeInformation__itemImgArea\"><img loading=\"lazy\" decoding=\"async\" class=\"p-storeInformation__itemImg\" alt=\"Room 1802, 18\/F, One Pacific Centre, 414 Kwun Tong Rd, Kwun Tong\" width=\"1280\" height=\"853\" src=\"\/wp-content\/uploads\/2023\/08\/HK-ALLU-Kwun-Tong_2.jpg\"><\/div><div class=\"p-storeInformation__itemBody\"><h3 class=\"p-storeInformation__itemTitle\">ALLU HK Kwun Tong Shop<\/h3><address class=\"p-storeInformation__itemAddress\">Room 1802, 18\/F, One Pacific Centre, 414 Kwun Tong Rd, Kwun Tong<\/address><div class=\"p-storeInformation__itemBtnArea\"><a class=\"p-storeInformation__itemBtn\" href=\"https:\/\/sell-hk.allu-official.com\/en\/shop\/kwun-tong-shop\/\">View ALLU HK Kwun Tong Shop Details<\/a><\/div><\/div><\/li><\/ul><\/div><\/section><\/div>\n\n<div class=\"lazyblock-qanda-ZAoyjC wp-block-lazyblock-qanda\">\n\n<\/div>\n\n<div class=\"lazyblock-brandlist-Z2sEyNA wp-block-lazyblock-brandlist\"><section class=\"p-brandModels\">\n    <h2 class=\"p-brandModels__title\">\n    Sell Your Jewellery and Gemstone Jewellery<\/h2>\n  <div class=\"p-brandModels__content\">\n    <h3 class=\"p-brandModels__subtitle\">\n      Gemstone Jewellery Types    <\/h3>\n    <ul class=\"p-brandModels__list\">\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/diamond\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-01.webp\" alt=\"Diamond\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Diamond<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/emerald\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-03.webp\" alt=\"Emerald\" width=\"154\" height=\"98\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Emerald<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/ruby\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-04.webp\" alt=\"Ruby\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Ruby<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/sapphire\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-05.webp\" alt=\"Sapphire\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Sapphire<\/span><\/p>\n        <\/a>\n      <\/li>\n                <\/ul>\n  <\/div>\n  \n  <div class=\"p-brandModels__content--mtSp\">\n    <h3 class=\"p-brandModels__subtitle\">Jewellery Brands<\/h3>\n    <ul class=\"p-brandModels__list\">\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/cartier\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-09.webp\" alt=\"Cartier\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Cartier<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/tiffany\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-10.webp\" alt=\"Tiffany &amp; Co.\" width=\"154\" height=\"98\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Tiffany &amp; Co.<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/vancleefarpels\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-11.webp\" alt=\"Van Cleef &amp; Arpels\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Van Cleef &amp; Arpels<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/bulgari\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-12.webp\" alt=\"Bulgari\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Bulgari<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/mikimoto\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-13.webp\" alt=\"Mikimoto\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Mikimoto<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/tasaki\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-tasaki.webp\" alt=\"Tasaki\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Tasaki<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/harrywinston\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-14.webp\" alt=\"Harry Winston\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Harry Winston<\/span><\/p>\n        <\/a>\n      <\/li>\n    <\/ul>\n  <\/div>\n  <p class=\"p-brandModels__btnArea\">\n    <a class=\"p-brandModels__btn\" href=\"\/en\/jewelry\/item-list\/\">&gt; Jewellery Item List<\/a>\n  <\/p>\n<\/section>\n<section class=\"p-brandModels\">\n  <h2 class=\"p-brandModels__title\">Sell Your Gold and Precious Metals<\/h2>\n  <div class=\"p-brandModels__content\">\n    <ul class=\"p-brandModels__list\">\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/gold\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/item-list\/btn-jw-02.webp\" alt=\"Gold and Precious Metals\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Gold and Precious Metals<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/gold\/platinum\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/item-list\/list-gold-platinum.webp\" alt=\"Platinum\" width=\"154\" height=\"98\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Platinum<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/gold\/silver\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/item-list\/list-gold-silver.webp\" alt=\"Silver\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Silver<\/span><\/p>\n        <\/a>\n      <\/li>\n    <\/ul>\n  <\/div>\n  <p class=\"p-brandModels__btnArea\"><a class=\"p-brandModels__btn\" href=\"\/en\/gold\/item-list\/\">&gt; Gold and Precious Metals Item List<\/a><\/p>\n<\/section><\/div>\n\n<div class=\"lazyblock-brandlist-Z5lqVv wp-block-lazyblock-brandlist\"><section class=\"p-brandModels\">\n    <h2 class=\"p-brandModels__title\">\n    Sell Your Jewellery and Gemstone Jewellery<\/h2>\n  <div class=\"p-brandModels__content\">\n    <h3 class=\"p-brandModels__subtitle\">\n      Gemstone Jewellery Types    <\/h3>\n    <ul class=\"p-brandModels__list\">\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/diamond\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-01.webp\" alt=\"Diamond\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Diamond<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/emerald\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-03.webp\" alt=\"Emerald\" width=\"154\" height=\"98\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Emerald<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/ruby\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-04.webp\" alt=\"Ruby\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Ruby<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/sapphire\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-05.webp\" alt=\"Sapphire\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Sapphire<\/span><\/p>\n        <\/a>\n      <\/li>\n                <\/ul>\n  <\/div>\n  \n  <div class=\"p-brandModels__content--mtSp\">\n    <h3 class=\"p-brandModels__subtitle\">Jewellery Brands<\/h3>\n    <ul class=\"p-brandModels__list\">\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/cartier\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-09.webp\" alt=\"Cartier\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Cartier<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/tiffany\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-10.webp\" alt=\"Tiffany &amp; Co.\" width=\"154\" height=\"98\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Tiffany &amp; Co.<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/vancleefarpels\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-11.webp\" alt=\"Van Cleef &amp; Arpels\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Van Cleef &amp; Arpels<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/bulgari\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-12.webp\" alt=\"Bulgari\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Bulgari<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/mikimoto\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-13.webp\" alt=\"Mikimoto\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Mikimoto<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/tasaki\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-tasaki.webp\" alt=\"Tasaki\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Tasaki<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/jewelry\/harrywinston\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/btn\/btn-jw-14.webp\" alt=\"Harry Winston\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Harry Winston<\/span><\/p>\n        <\/a>\n      <\/li>\n    <\/ul>\n  <\/div>\n  <p class=\"p-brandModels__btnArea\">\n    <a class=\"p-brandModels__btn\" href=\"\/en\/jewelry\/item-list\/\">&gt; Jewellery Item List<\/a>\n  <\/p>\n<\/section>\n<section class=\"p-brandModels\">\n  <h2 class=\"p-brandModels__title\">Sell Your Gold and Precious Metals<\/h2>\n  <div class=\"p-brandModels__content\">\n    <ul class=\"p-brandModels__list\">\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/gold\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/item-list\/btn-jw-02.webp\" alt=\"Gold and Precious Metals\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Gold and Precious Metals<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/gold\/platinum\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/item-list\/list-gold-platinum.webp\" alt=\"Platinum\" width=\"154\" height=\"98\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Platinum<\/span><\/p>\n        <\/a>\n      <\/li>\n      <li class=\"p-brandModels__listItem\">\n        <a class=\"p-brandModels__listLink\" href=\"\/en\/gold\/silver\/\">\n          <p class=\"p-brandModels__listImgArea\"><img class=\"p-brandModels__listImg\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/jewelry\/item-list\/list-gold-silver.webp\" alt=\"Silver\" width=\"154\" height=\"155\" loading=\"lazy\" decoding=\"async\" \/><\/p>\n          <p class=\"p-brandModels__listName\"><span class=\"p-brandModels__listNameInner\">Silver<\/span><\/p>\n        <\/a>\n      <\/li>\n    <\/ul>\n  <\/div>\n  <p class=\"p-brandModels__btnArea\"><a class=\"p-brandModels__btn\" href=\"\/en\/gold\/item-list\/\">&gt; Gold and Precious Metals Item List<\/a><\/p>\n<\/section><\/div>\n\n<div class=\"lazyblock-cta-Z81n0l wp-block-lazyblock-cta\"><div class=\"p-cta\">\n  <div class=\"p-cta__inner\">\n    <div class=\"p-cta__title\">\n            <p class=\"p-cta__titleText\">\n                How to Sell Luxury Goods at ALLU              <\/p>\n    <\/div>\n    <ul class=\"p-cta__list\">\n      <li class=\"p-cta__listItem--shop\">\n        <a href=\"\/en\/store-service\/\" class=\"p-cta__listLink--shop\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Sell to Store\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_store.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">\n                        Sell at Store                        <\/p>\n            <p class=\"p-cta__listLinkSub\">\n                        The quickest way to get cash                        <\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n      <\/li>\n                  <li class=\"p-cta__listItem--whats\">\n                <a target=\"_blank\" href=\"https:\/\/api.whatsapp.com\/send?phone=85253630726&#038;text=%E6%82%A8%E5%A5%BD%EF%BC%8C%E6%88%91%E6%83%B3%E4%BA%86%E8%A7%A3%E6%9B%B4%E5%A4%9A%E5%9C%A8ALLU%E7%B6%B2%E4%B8%8A%E4%BC%B0%E5%83%B9\/%E5%88%B0%E5%BA%97%E6%94%BE%E5%94%AE%E8%A9%B3%E6%83%85%EF%BC%81\" class=\"p-cta__listLink--whats\">\n          <p class=\"p-cta__listLinkIcon\"><img decoding=\"async\" class=\"p-cta__listLinkIconImg\" alt=\"Chat on WhatsApp\" src=\"https:\/\/sell-hk.allu-official.com\/wp-content\/themes\/allu-global\/assets\/img\/common\/icon_cta_sns.svg\"><\/p>\n          <div class=\"p-cta__listLinkBox\">\n            <p class=\"p-cta__listLinkTitle\">Chat on WhatsApp<\/p>\n            <p class=\"p-cta__listLinkSub\">Contact Us<\/p>\n          <\/div>\n          <div class=\"p-cta__listLinkArrow\"><\/div>\n        <\/a>\n              <\/li>\n    <\/ul>\n  <\/div>\n<\/div><\/div>\n\n<div class=\"lazyblock-qanda-Z2uxKt0 wp-block-lazyblock-qanda\">\n\n<section class=\"p-qanda\" id=\"brand-qanda\">\n  <div class=\"p-qanda__inner\">\n    <h2 class=\"p-qanda__title\">ALLU Frequently Asked Questions<\/h2>    <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Can I sell items that are broken or in poor condition?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes, we can often purchase such items.<br \/>\n<br \/>\n      Items that are worn<br \/>\n      Items that are scratched or dirty<br \/>\n      Items with missing gemstones<br \/>\n      Items with older designs<br \/>\n<br \/>\n      If you ever were refused by other stores when trying to sell your item for reasons such as the above, please visit us at ALLU.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Can I still sell items without a certificate of authenticity?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes. Even if you do not have a certificate of authenticity, our experienced Value Designers will carefully and accurately evaluate your jewellery.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Can I sell loose or rough gemstones?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes. In many cases \u2014 especially in the case of diamonds \u2014 if the grade is high, you can sell even loose gemstones at high prices.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Can I sell non-branded jewellery?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes, you can sell jewellery at ALLU regardless of the brand.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">I received a higher selling price at another store.<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        We will do our best to meet your expectations, so please let us know how much the other company&#8217;s evaluation was.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Do selling prices vary from store to store?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        No. All of our stores use the same standards for evaluation.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">Do I need to make an appointment?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        Yes. We ask that customers make an appointment via WhatsApp first so we can make sure that the appraisal can go smoothly.      <\/div>\n    <\/div>\n        <div class=\"p-qanda__accordion\">\n      <p class=\"p-qanda__accordionTitle js-commonAccordion\">How long does it take for an appraisal at the store?<\/p>\n      <div class=\"p-qanda__accordionBody\">\n        We estimate 10 to 15 minutes for a single item. It depends on the item and the quantity, so please ask our staff when you visit.      <\/div>\n    <\/div>\n      <\/div>\n<\/section>\n\n<script type=\"application\/ld+json\">\n  {\n      \"@context\": \"https:\/\/schema.org\",\n      \"@id\":\"#FAQContents\",\n      \"@type\": \"FAQPage\",\n      \"mainEntity\": [\n                {\n          \"@type\": \"Question\",\n          \"name\": \"Can I sell items that are broken or in poor condition?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes, we can often purchase such items.      Items that are worn      Items that are scratched or dirty      Items with missing gemstones      Items with older designs      If you ever were refused by other stores when trying to sell your item for reasons such as the above, please visit us at ALLU.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Can I still sell items without a certificate of authenticity?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes. Even if you do not have a certificate of authenticity, our experienced Value Designers will carefully and accurately evaluate your jewellery.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Can I sell loose or rough gemstones?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes. In many cases \u2014 especially in the case of diamonds \u2014 if the grade is high, you can sell even loose gemstones at high prices.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Can I sell non-branded jewellery?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes, you can sell jewellery at ALLU regardless of the brand.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"I received a higher selling price at another store.\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"We will do our best to meet your expectations, so please let us know how much the other company&#039;s evaluation was.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Do selling prices vary from store to store?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"No. All of our stores use the same standards for evaluation.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"Do I need to make an appointment?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"Yes. We ask that customers make an appointment via WhatsApp first so we can make sure that the appraisal can go smoothly.\"\n          }\n        },                {\n          \"@type\": \"Question\",\n          \"name\": \"How long does it take for an appraisal at the store?\",\n          \"acceptedAnswer\": {\n              \"@type\": \"Answer\",\n              \"text\": \"We estimate 10 to 15 minutes for a single item. It depends on the item and the quantity, so please ask our staff when you visit.\"\n          }\n        }              ]\n  }\n<\/script>\n<\/div>","protected":false},"featured_media":0,"parent":0,"menu_order":0,"template":"","format":"standard","meta":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/jewelry\/1922"}],"collection":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/jewelry"}],"about":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/types\/jewelry"}],"version-history":[{"count":5,"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/jewelry\/1922\/revisions"}],"predecessor-version":[{"id":7715,"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/jewelry\/1922\/revisions\/7715"}],"wp:attachment":[{"href":"https:\/\/sell-hk.allu-official.com\/en\/wp-json\/wp\/v2\/media?parent=1922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}